{"id":6044,"date":"2019-11-25T17:02:53","date_gmt":"2019-11-25T22:02:53","guid":{"rendered":"https:\/\/www.elastoproxy.com\/?p=6044"},"modified":"2021-02-03T15:45:15","modified_gmt":"2021-02-03T20:45:15","slug":"reduire-vos-couts-de-main-doeuvre","status":"publish","type":"post","link":"https:\/\/www.elastoproxy.com\/fr\/reduire-vos-couts-de-main-doeuvre\/","title":{"rendered":"Cinq fa\u00e7ons pour r\u00e9duire vos co\u00fbts de main-d\u2019\u0153uvre"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"6044\" class=\"elementor elementor-6044\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c4690ef elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c4690ef\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-24811df\" data-id=\"24811df\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-07edb3c elementor-widget elementor-widget-text-editor\" data-id=\"07edb3c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Quels sont vos objectifs commerciaux pour l\u2019ann\u00e9e \u00e0 venir ? Si vous \u00eates comme beaucoup de fabricants, vous esp\u00e9rez embaucher plus de travailleurs qualifi\u00e9s. Toutefois, <a href=\"https:\/\/www.bbc.com\/news\/business-49934309\">le taux de ch\u00f4mage reste faible<\/a> et certaines entreprises constatent qu\u2019elles doivent payer une prime uniquement pour garder leurs travailleurs. \u00cates-vous pr\u00eat \u00e0 absorber la d\u00e9pense suppl\u00e9mentaire ? M\u00eame si vos ventes augmentent fortement il est important de trouver des moyens pour r\u00e9duire les co\u00fbts de main-d\u2019\u0153uvre.<\/p><p>Voici cinq conseils \u00e0 prendre en compte lorsque vous planifiez une ann\u00e9e 2020 rentable:<\/p><ul><li>Enqu\u00eatez sur l\u2019externalisation<\/li><li>Utilisez les bons mat\u00e9riaux<\/li><li>Simplifiez la r\u00e9ception et l\u2019inventaire<\/li><li>Boostez l\u2019assemblage<\/li><li>Facilitez l\u2019installation<\/li><\/ul><p>Examinons maintenant chaque conseil en termes de fabrication de joints d\u2019\u00e9tanch\u00e9it\u00e9 reposant sur <a href=\"https:\/\/www.elastoproxy.com\/added-value-sevices\">des services \u00e0 valuer ajout\u00e9e<\/a>.<strong>\u00a0<\/strong><\/p><h2><strong># 1 Enqu\u00eatez sur l\u2019externalisation<\/strong><\/h2><p>Est-ce que vous coupez les joints avec des outils \u00e0 main pour ensuite coller les longueurs coup\u00e9es \u00e0 la main ? Certains fabricants pensent que la fabrication d\u2019un joint co\u00fbte toujours moins cher lorsqu\u2019elle est r\u00e9alis\u00e9e en interne. Toutefois, ces entreprises ne tiennent pas compte du fait que les salaires de leurs employ\u00e9s peuvent \u00eatre sup\u00e9rieurs au taux de la main-d\u2019\u0153uvre chez un fabricant de joints. <a href=\"https:\/\/www.elastoproxy.com\/reducing-shop-waste\/\">Si vous payez un soudeur<\/a> qui gagne 25 $\/heure pour couper et coller le caoutchouc, vos joints co\u00fbteront s\u00fbrement plus cher que ceux fabriqu\u00e9s chez un fabricant de joints o\u00f9 les employ\u00e9s gagnent 15 $\/heure. De plus, bien que les soudeurs soient des ouvriers m\u00e9tallurgistes qualifi\u00e9s, ils peuvent s\u2019av\u00e9rer moins efficaces qu\u2019un \u00ab\u00a0ouvrier du caoutchouc\u00a0\u00bb qui fabrique des joints tous les jours.<\/p><h2><strong># 2 Utilisez les bons mat\u00e9riaux<\/strong><\/h2><p>Choisir le bon mat\u00e9riau signifie comprendre quand un <a href=\"https:\/\/www.elastoproxy.com\/commercial-grade-rubber-vs-specialty-rubber\/\">compos\u00e9 sp\u00e9cial<\/a> est n\u00e9cessaire et quand un caoutchouc de qualit\u00e9 commerciale est suffisant. Les ing\u00e9nieurs veulent s\u2019assurer que les produits qu\u2019ils con\u00e7oivent r\u00e9pondent aux exigences de l\u2019application, mais une sp\u00e9cification excessive d\u2019un \u00e9lastom\u00e8re peut entra\u00eener des co\u00fbts inutiles. En plus de payer davantage par unit\u00e9 de mat\u00e9riel, vous devrez peut-\u00eatre acheter de plus grandes quantit\u00e9s minimum de commande (MOQ). Avant donc d\u2019ajouter une exigence du type \u00ab\u00a0Caoutchouc UL 50\u00a0\u00bb \u00e0 un dessin, d\u00e9terminez si c\u2019est vraiment n\u00e9cessaire. Si vous avez besoin de \u00ab\u00a0caoutchouc ASTM\u00a0\u00bb, d\u00e9terminez la norme alphanum\u00e9rique \u00e0 respecter.<\/p><h2><strong># 3 Simplifiez la r\u00e9ception et l&rsquo;inventaire<\/strong><\/h2><p>Achetez-vous plusieurs types de joints finis pour un projet ? R\u00e9fl\u00e9chissez donc \u00e0 la mani\u00e8re dont le <a href=\"https:\/\/www.elastoproxy.com\/added-value-sevices\/kitting\/\">marquage des kits d\u2019assemblage<\/a> et <a href=\"https:\/\/www.elastoproxy.com\/added-value-sevices\/uv-parts-marking\/\">des pi\u00e8ces UV<\/a> peut simplifier vos op\u00e9rations de r\u00e9ception et d\u2019inventaire. Au lieu de traiter plusieurs bo\u00eetes avec diff\u00e9rentes UGS (Unit\u00e9s de gestion de stock), un r\u00e9cepteur peut g\u00e9rer une seule bo\u00eete &#8211; un kit &#8211; qui contient tous les joints n\u00e9cessaires. Avec un inventaire juste \u00e0 temps (JIT), la bo\u00eete peut m\u00eame ne pas avoir besoin de stockage. Le kit peut plut\u00f4t passer directement de la zone de r\u00e9ception \u00e0 la cha\u00eene de montage. Ensuite, \u00e9tant donn\u00e9 que les pi\u00e8ces jointes arrivent clairement indiqu\u00e9es, il n\u2019y a pas de confusion quant aux num\u00e9ros de pi\u00e8ce. Le marquage UV des pi\u00e8ces est net, propre et facile \u00e0 lire.<\/p><h2><strong># 4 l\u2019Assemblage en vitesse<\/strong><\/h2><p><a href=\"https:\/\/www.elastoproxy.com\/added-value-sevices\/custom-packaging\/\">Les emballages faits sur mesure<\/a> compl\u00e8tent le marquage des kits et des pi\u00e8ces. Ce service \u00e0 valeur ajout\u00e9e peut \u00e9galement vous aider \u00e0 r\u00e9duire les co\u00fbts de main-d\u2019\u0153uvre. Supposons que vous ayez besoin d\u2019un kit contenant diff\u00e9rents types d\u2019isolation pour la cabine d\u2019un v\u00e9hicule sp\u00e9cialis\u00e9. Elasto Proxy peut organiser l\u2019isolation acoustique et le rev\u00eatement de sol dans l\u2019ordre d\u2019assemblage pour des op\u00e9rations plus efficaces. En d\u2019autres termes, la partie la plus importante est celle qui a \u00e9t\u00e9 install\u00e9e en premier. La partie au bas de la bo\u00eete est celle qui a \u00e9t\u00e9 install\u00e9e en dernier. Cela permet \u00e0 l\u2019assembleur de commencer avec le plafond de la cabine, d\u2019\u0153uvrer le long des murs vers le bas et de terminer avec le rev\u00eatement de sol.<\/p><h2><strong># 5 Facilitez l\u2019installation<\/strong><\/h2><p>Les fabricants dans des industries telles que les \u00e9quipements mobiles utilisent parfois <a href=\"https:\/\/www.elastoproxy.com\/custom-cab-insulation\/\">une pulv\u00e9risation adh\u00e9sive<\/a> pour attacher un isolant thermique ou acoustique. La pulv\u00e9risation peut n\u00e9cessiter le respect de nombreuses r\u00e9glementations en mati\u00e8re de sant\u00e9 et de s\u00e9curit\u00e9, ainsi que des activit\u00e9s de pr\u00e9paration et de nettoyage intensives. En revanche, les isolants sur mesure peuvent \u00eatre attach\u00e9s \u00e0 l\u2019aide d\u2019un ruban adh\u00e9sif sensible \u00e0 la pression (PSA). Votre installateur enl\u00e8ve simplement le mat\u00e9riau de support et colle l\u2019isolant acoustique \u00e0 la surface de la cabine.<\/p><h2><strong>R\u00e9duisez vos co\u00fbts de main-d\u2019\u0153uvre en 2020<\/strong><strong>\u00a0<\/strong><\/h2><p>Souhaitez-vous r\u00e9duire vos co\u00fbts de main-d\u2019\u0153uvre en 2020 ? Elasto Proxy est pr\u00eate \u00e0 vous aider \u00e0 d\u00e9marrer. Au lieu de couper et coller le joint \u00e0 la main, posez-nous des questions sur la d\u00e9coupe par jet d\u2019eau command\u00e9e par ordinateur et votre choix de m\u00e9thodes de collage. En plus de la fabrication sur mesure, Elasto Proxy propose des services \u00e0 valeur ajout\u00e9e tels que l\u2019assistance \u00e0 la conception, l\u2019aide au choix des mat\u00e9riaux, le marquage des pi\u00e8ces, la mise en kit et l\u2019emballage sur mesure. N\u2019attendez pas le 1er janvier pour commencer \u00e0 \u00e9conomiser en temps et en argent.<\/p><p><a href=\"https:\/\/www.elastoproxy.com\/contact-us\/\">Contactez-nous pour commencer<\/a>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Quels sont vos objectifs commerciaux pour l\u2019ann\u00e9e \u00e0 venir ? Si vous \u00eates comme beaucoup de fabricants, vous esp\u00e9rez embaucher plus de travailleurs qualifi\u00e9s. Toutefois, le taux de ch\u00f4mage reste faible et certaines entreprises constatent qu\u2019elles doivent payer une prime uniquement pour garder leurs travailleurs. \u00cates-vous pr\u00eat \u00e0 absorber la d\u00e9pense suppl\u00e9mentaire ? M\u00eame si [&hellip;]<\/p>\n","protected":false},"author":20,"featured_media":4191,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ofc_enable_fullscreen":"disable","ofc_fullscreen_speed":0,"ofc_fullscreen_nav":"enable","ofc_fullscreen_nav_pos":"right","ofc_fullscreen_nav_color":"","ofc_fullscreen_nav_tooltip_color":"","ofc_fullscreen_responsive":0,"osh_disable_topbar_sticky":"default","osh_disable_header_sticky":"default","osh_sticky_header_style":"default","osh_sticky_header_effect":"","osh_custom_sticky_logo":0,"osh_custom_retina_sticky_logo":0,"osh_custom_sticky_logo_height":0,"osh_background_color":"","osh_links_color":"","osh_links_hover_color":"","osh_links_active_color":"","osh_links_bg_color":"","osh_links_hover_bg_color":"","osh_links_active_bg_color":"","osh_menu_social_links_color":"","osh_menu_social_hover_links_color":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"off","ocean_gallery_id":[],"footnotes":""},"categories":[1],"tags":[1011,602,568,1008,1007,1009,1010],"class_list":["post-6044","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-coutsdemain-doeuvre","tag-fabricant","tag-fabrication","tag-couts-de-main-doeuvre","tag-employes","tag-la-main-doeuvre","tag-travailleurs","entry","has-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Reduire vos co\u00fbts de main-d\u2019\u0153uvre | Cinq fa\u00e7ons d\u2019\u00e9conomiser<\/title>\n<meta name=\"description\" content=\"M\u00eame si vos ventes augmentent fortement, il est utile de trouver des moyens pour r\u00e9duire vos co\u00fbts de main-d\u2019\u0153uvre. r\u00e9duire vos co\u00fbts de main-d\u2019\u0153uvre\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.elastoproxy.com\/fr\/reduire-vos-couts-de-main-doeuvre\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reduire vos co\u00fbts de main-d\u2019\u0153uvre | Cinq fa\u00e7ons d\u2019\u00e9conomiser\" \/>\n<meta property=\"og:description\" content=\"M\u00eame si vos ventes augmentent fortement, il est utile de trouver des moyens pour r\u00e9duire vos co\u00fbts de main-d\u2019\u0153uvre. r\u00e9duire vos co\u00fbts de main-d\u2019\u0153uvre\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.elastoproxy.com\/fr\/reduire-vos-couts-de-main-doeuvre\/\" \/>\n<meta property=\"og:site_name\" content=\"Elasto Proxy\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-25T22:02:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-03T20:45:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.elastoproxy.com\/wp-content\/uploads\/2018\/12\/DSC_0014.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"3008\" \/>\n\t<meta property=\"og:image:height\" content=\"2000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Steve Melito\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Steve Melito\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reduire vos co\u00fbts de main-d\u2019\u0153uvre | Cinq fa\u00e7ons d\u2019\u00e9conomiser","description":"M\u00eame si vos ventes augmentent fortement, il est utile de trouver des moyens pour r\u00e9duire vos co\u00fbts de main-d\u2019\u0153uvre. r\u00e9duire vos co\u00fbts de main-d\u2019\u0153uvre","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.elastoproxy.com\/fr\/reduire-vos-couts-de-main-doeuvre\/","og_locale":"fr_FR","og_type":"article","og_title":"Reduire vos co\u00fbts de main-d\u2019\u0153uvre | Cinq fa\u00e7ons d\u2019\u00e9conomiser","og_description":"M\u00eame si vos ventes augmentent fortement, il est utile de trouver des moyens pour r\u00e9duire vos co\u00fbts de main-d\u2019\u0153uvre. r\u00e9duire vos co\u00fbts de main-d\u2019\u0153uvre","og_url":"https:\/\/www.elastoproxy.com\/fr\/reduire-vos-couts-de-main-doeuvre\/","og_site_name":"Elasto Proxy","article_published_time":"2019-11-25T22:02:53+00:00","article_modified_time":"2021-02-03T20:45:15+00:00","og_image":[{"width":3008,"height":2000,"url":"https:\/\/www.elastoproxy.com\/wp-content\/uploads\/2018\/12\/DSC_0014.jpg","type":"image\/jpeg"}],"author":"Steve Melito","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Steve Melito","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.elastoproxy.com\/fr\/reduire-vos-couts-de-main-doeuvre\/#article","isPartOf":{"@id":"https:\/\/www.elastoproxy.com\/fr\/reduire-vos-couts-de-main-doeuvre\/"},"author":{"name":"Steve Melito","@id":"https:\/\/www.elastoproxy.com\/#\/schema\/person\/54c278304f2b3726bb8de1bb1b5df225"},"headline":"Cinq fa\u00e7ons pour r\u00e9duire vos co\u00fbts de main-d\u2019\u0153uvre","datePublished":"2019-11-25T22:02:53+00:00","dateModified":"2021-02-03T20:45:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.elastoproxy.com\/fr\/reduire-vos-couts-de-main-doeuvre\/"},"wordCount":945,"commentCount":0,"publisher":{"@id":"https:\/\/www.elastoproxy.com\/#organization"},"image":{"@id":"https:\/\/www.elastoproxy.com\/fr\/reduire-vos-couts-de-main-doeuvre\/#primaryimage"},"thumbnailUrl":"https:\/\/www.elastoproxy.com\/wp-content\/uploads\/2018\/12\/DSC_0014.jpg","keywords":["#co\u00fbtsdemain-d\u2019\u0153uvre","#Fabricant","#Fabrication","co\u00fbts de main-d\u2019\u0153uvre","employ\u00e9s","la main d\u2019oeuvre","travailleurs"],"articleSection":["News"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.elastoproxy.com\/fr\/reduire-vos-couts-de-main-doeuvre\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.elastoproxy.com\/fr\/reduire-vos-couts-de-main-doeuvre\/","url":"https:\/\/www.elastoproxy.com\/fr\/reduire-vos-couts-de-main-doeuvre\/","name":"Reduire vos co\u00fbts de main-d\u2019\u0153uvre | Cinq fa\u00e7ons d\u2019\u00e9conomiser","isPartOf":{"@id":"https:\/\/www.elastoproxy.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.elastoproxy.com\/fr\/reduire-vos-couts-de-main-doeuvre\/#primaryimage"},"image":{"@id":"https:\/\/www.elastoproxy.com\/fr\/reduire-vos-couts-de-main-doeuvre\/#primaryimage"},"thumbnailUrl":"https:\/\/www.elastoproxy.com\/wp-content\/uploads\/2018\/12\/DSC_0014.jpg","datePublished":"2019-11-25T22:02:53+00:00","dateModified":"2021-02-03T20:45:15+00:00","description":"M\u00eame si vos ventes augmentent fortement, il est utile de trouver des moyens pour r\u00e9duire vos co\u00fbts de main-d\u2019\u0153uvre. r\u00e9duire vos co\u00fbts de main-d\u2019\u0153uvre","breadcrumb":{"@id":"https:\/\/www.elastoproxy.com\/fr\/reduire-vos-couts-de-main-doeuvre\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.elastoproxy.com\/fr\/reduire-vos-couts-de-main-doeuvre\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.elastoproxy.com\/fr\/reduire-vos-couts-de-main-doeuvre\/#primaryimage","url":"https:\/\/www.elastoproxy.com\/wp-content\/uploads\/2018\/12\/DSC_0014.jpg","contentUrl":"https:\/\/www.elastoproxy.com\/wp-content\/uploads\/2018\/12\/DSC_0014.jpg","width":3008,"height":2000,"caption":"Reduce Your Labor Costs | r\u00e9duire vos co\u00fbts de main-d\u2019\u0153uvre"},{"@type":"BreadcrumbList","@id":"https:\/\/www.elastoproxy.com\/fr\/reduire-vos-couts-de-main-doeuvre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.elastoproxy.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Cinq fa\u00e7ons pour r\u00e9duire vos co\u00fbts de main-d\u2019\u0153uvre"}]},{"@type":"WebSite","@id":"https:\/\/www.elastoproxy.com\/#website","url":"https:\/\/www.elastoproxy.com\/","name":"Elasto Proxy","description":"Rubber Fabricator and Distributor","publisher":{"@id":"https:\/\/www.elastoproxy.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.elastoproxy.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.elastoproxy.com\/#organization","name":"Elasto Proxy","url":"https:\/\/www.elastoproxy.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.elastoproxy.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.elastoproxy.com\/wp-content\/uploads\/2018\/10\/logo-elastoproxy.png","contentUrl":"https:\/\/www.elastoproxy.com\/wp-content\/uploads\/2018\/10\/logo-elastoproxy.png","width":200,"height":61,"caption":"Elasto Proxy"},"image":{"@id":"https:\/\/www.elastoproxy.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.elastoproxy.com\/#\/schema\/person\/54c278304f2b3726bb8de1bb1b5df225","name":"Steve Melito","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.elastoproxy.com\/#\/schema\/person\/image\/","url":"https:\/\/www.elastoproxy.com\/wp-content\/litespeed\/avatar\/cf7233bebd28fab336564db23356c33b.jpg?ver=1788262653","contentUrl":"https:\/\/www.elastoproxy.com\/wp-content\/litespeed\/avatar\/cf7233bebd28fab336564db23356c33b.jpg?ver=1788262653","caption":"Steve Melito"},"url":"https:\/\/www.elastoproxy.com\/fr\/author\/smelito\/"}]}},"_links":{"self":[{"href":"https:\/\/www.elastoproxy.com\/fr\/wp-json\/wp\/v2\/posts\/6044","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elastoproxy.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.elastoproxy.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.elastoproxy.com\/fr\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elastoproxy.com\/fr\/wp-json\/wp\/v2\/comments?post=6044"}],"version-history":[{"count":4,"href":"https:\/\/www.elastoproxy.com\/fr\/wp-json\/wp\/v2\/posts\/6044\/revisions"}],"predecessor-version":[{"id":11602,"href":"https:\/\/www.elastoproxy.com\/fr\/wp-json\/wp\/v2\/posts\/6044\/revisions\/11602"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.elastoproxy.com\/fr\/wp-json\/wp\/v2\/media\/4191"}],"wp:attachment":[{"href":"https:\/\/www.elastoproxy.com\/fr\/wp-json\/wp\/v2\/media?parent=6044"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.elastoproxy.com\/fr\/wp-json\/wp\/v2\/categories?post=6044"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.elastoproxy.com\/fr\/wp-json\/wp\/v2\/tags?post=6044"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}