{"id":5258,"date":"2019-07-13T07:57:51","date_gmt":"2019-07-13T11:57:51","guid":{"rendered":"https:\/\/www.elastoproxy.com\/?p=5258"},"modified":"2021-03-01T16:14:42","modified_gmt":"2021-03-01T21:14:42","slug":"nitrile-ou-neoprene","status":"publish","type":"post","link":"https:\/\/www.elastoproxy.com\/fr\/nitrile-ou-neoprene\/","title":{"rendered":"Nitrile ou n\u00e9opr\u00e8ne, pour sceaux, joints d&rsquo;\u00e9tanch\u00e9it\u00e9 et isolants en caoutchouc"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"5258\" class=\"elementor elementor-5258 elementor-bc-flex-widget\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cf8940b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cf8940b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-79e08cd\" data-id=\"79e08cd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-371a850 elementor-widget elementor-widget-text-editor\" data-id=\"371a850\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Quelle est la diff\u00e9rence entre le nitrile et le n\u00e9opr\u00e8ne pour les sceaux, les joints d\u2019\u00e9tanch\u00e9it\u00e9 et les isolants ? Ces deux \u00e9lastom\u00e8res offrent une bonne r\u00e9sistance \u00e0 la compression r\u00e9manente et \u00e0 la d\u00e9chirure. Ils supportent \u00e9galement les m\u00eames temp\u00e9ratures de service. Certaines qualit\u00e9s de n\u00e9opr\u00e8ne offrent une excellente r\u00e9sistance \u00e0 l&rsquo;abrasion, mais le nitrile est connu pour sa r\u00e9sistance \u00e0 l&rsquo;abrasion \u00e0 des temp\u00e9ratures \u00e9lev\u00e9es.<\/p><p>Les caoutchoucs en nitrile et en n\u00e9opr\u00e8ne ont de nombreuses similitudes, mais il y a aussi des diff\u00e9rences importantes entre ces 2 \u00e9lastom\u00e8res. Dans cet article d\u2019Elasto Proxy vous apprendrez quand il faut utiliser le nitrile plut\u00f4t que le n\u00e9opr\u00e8ne. Vous comparerez \u00e9galement ces compos\u00e9s courants \u00e0 une liste compl\u00e8te de propri\u00e9t\u00e9s de mat\u00e9riau afin de pouvoir faire le bon choix pour votre application.<\/p><h2><strong>Nitrile ou N\u00e9opr\u00e8ne: Propri\u00e9t\u00e9s de ces 2 mat\u00e9riaux<\/strong><\/h2><p>Le <a href=\"https:\/\/www.elastoproxy.com\/?p=3246\">nitrile<\/a> offre une excellente r\u00e9sistance \u00e0 l&rsquo;huile et aux solvants dans une large gamme de temp\u00e9ratures. Cet \u00e9lastom\u00e8re synth\u00e9tique a une tr\u00e8s bonne r\u00e9sistance \u00e0 l&rsquo;huile de moteur et \u00e0 l&rsquo;essence ou le gazole, une tr\u00e8s bonne r\u00e9sistance aux alcalis et aux acides et une r\u00e9sistance sup\u00e9rieure aux fluides hydrauliques \u00e0 base de p\u00e9trole. Le <a href=\"https:\/\/www.elastoproxy.com\/blog\/neoprene-rubber-sealing-insulation\/\">n\u00e9opr\u00e8ne<\/a> offre une r\u00e9sistance mod\u00e9r\u00e9e aux huiles et aux produits p\u00e9troliers, mais une r\u00e9sistance nettement sup\u00e9rieure aux rayons de soleil, \u00e0 l&rsquo;ozone et aux intemp\u00e9ries.<\/p><p>Les diff\u00e9rences ne s&rsquo;arr\u00eatent pas l\u00e0 pour autant. Le caoutchouc en nitrile a une faible r\u00e9sistance au feu. En revanche, le n\u00e9opr\u00e8ne offre une tr\u00e8s bonne \u00e0 excellente r\u00e9sistance contre la propagation d&rsquo;un incendie. Le nitrile est attaqu\u00e9 par la lumi\u00e8re du soleil, l&rsquo;ozone et les intemp\u00e9ries, mais le n\u00e9opr\u00e8ne offre une r\u00e9sistance fiable contre ces conditions environnementales. Pourtant, aucun de ces deux caoutchoucs ne r\u00e9siste aux aromates ni aux c\u00e9tones, deux types de compos\u00e9s organiques.<\/p><p>Les tableaux suivants comparent en d\u00e9tail le nitrile au n\u00e9opr\u00e8ne.<\/p><table width=\"813\"><tbody><tr><td colspan=\"2\" width=\"271\"><p>\u00a0<\/p><\/td><td colspan=\"2\" width=\"271\"><p>\u00a0<\/p><\/td><td width=\"271\"><p>\u00a0<\/p><\/td><\/tr><tr><td width=\"174\"><h3><strong>Information g\u00e9n\u00e9rale<\/strong><\/h3><\/td><td colspan=\"2\" width=\"222\"><h3><strong>Caoutchouc\u00a0 en nitrile<\/strong><\/h3><\/td><td colspan=\"2\" width=\"417\"><h3><strong>Caoutchouc en n\u00e9opr\u00e8ne<\/strong><\/h3><\/td><\/tr><tr><td width=\"174\"><p>Appellations courantes<\/p><\/td><td colspan=\"2\" width=\"222\"><p>Nitrile, Buna-N, NBR<\/p><\/td><td colspan=\"2\" width=\"417\"><p>N\u00e9opr\u00e8ne<\/p><\/td><\/tr><tr><td width=\"174\"><p>Appellations chimiques<\/p><\/td><td colspan=\"2\" width=\"222\"><p>Acrylonitrile-butadiene<\/p><\/td><td colspan=\"2\" width=\"417\"><p>polychloropr\u00e8ne<\/p><\/td><\/tr><tr><td width=\"174\"><p>Classification ASTM D-2000<\/p><\/td><td colspan=\"2\" width=\"222\"><p>BF, BG, BK, CH<\/p><\/td><td colspan=\"2\" width=\"417\"><p>BC, BE<\/p><\/td><\/tr><tr><td width=\"174\"><p>\u00a0<\/p><\/td><td colspan=\"2\" width=\"222\"><p>\u00a0<\/p><\/td><td colspan=\"2\" width=\"417\"><p>\u00a0<\/p><\/td><\/tr><tr><td width=\"174\"><h2><strong>Caract\u00e9ristiques physiques<\/strong><\/h2><\/td><td colspan=\"2\" width=\"222\"><h3><strong>Caoutchouc en nitrile<\/strong><\/h3><\/td><td colspan=\"2\" width=\"417\"><h3><strong>Caoutchouc en n\u00e9opr\u00e8ne<\/strong><\/h3><\/td><\/tr><tr><td width=\"174\"><p>\u00c9longation<\/p><\/td><td colspan=\"2\" width=\"222\"><p>De 400% \u00e0 600%<\/p><\/td><td colspan=\"2\" width=\"417\"><p>De 100% \u00e0 800%<\/p><\/td><\/tr><tr><td width=\"174\"><p>Duret\u00e9 (Shore A)<\/p><\/td><td colspan=\"2\" width=\"222\"><p>De 35 \u00e0 90<\/p><\/td><td colspan=\"2\" width=\"417\"><p>De 15 \u00e0 95<\/p><\/td><\/tr><tr><td width=\"174\"><h3>\u00a0<\/h3><\/td><td colspan=\"2\" width=\"222\"><h3>\u00a0<\/h3><\/td><td colspan=\"2\" width=\"417\"><h3>\u00a0<\/h3><\/td><\/tr><tr><td width=\"174\"><h3><strong>Caract\u00e9ristiques m\u00e9caniques<\/strong><\/h3><\/td><td colspan=\"2\" width=\"222\"><h3><strong>Caoutchouc en nitrile <\/strong><\/h3><\/td><td colspan=\"2\" width=\"417\"><h3><strong>Caoutchouc en n\u00e9opr\u00e8ne <\/strong><\/h3><\/td><\/tr><tr><td width=\"174\"><p>Compression r\u00e9manente<\/p><\/td><td colspan=\"2\" width=\"222\"><p>Bonne<\/p><\/td><td colspan=\"2\" width=\"417\"><p>Bonne<\/p><\/td><\/tr><tr><td width=\"174\"><p>Cote de rebondissement<\/p><\/td><td colspan=\"2\" width=\"222\"><p>Bonne<\/p><\/td><td colspan=\"2\" width=\"417\"><p>Bonne \u00e0 tr\u00e8s bonne<\/p><\/td><\/tr><tr><td width=\"174\"><p>R\u00e9sistance \u00e0 la fissuration due \u00e0 la flexion<\/p><\/td><td colspan=\"2\" width=\"222\"><p>Bonne<\/p><\/td><td colspan=\"2\" width=\"417\"><p>Bonne \u00e0 tr\u00e8s bonne<\/p><\/td><\/tr><tr><td width=\"174\"><p>R\u00e9sistance \u00e0 l\u2019abrasion<\/p><\/td><td colspan=\"2\" width=\"222\"><p>Bonne \u00e0 excellente<\/p><\/td><td colspan=\"2\" width=\"417\"><p>Tr\u00e8s bonne \u00e0 excellente<\/p><\/td><\/tr><tr><td width=\"174\"><p>R\u00e9sistance \u00e0 la d\u00e9chirure<\/p><\/td><td colspan=\"2\" width=\"222\"><p>Bonne<\/p><\/td><td colspan=\"2\" width=\"417\"><p>Bonne<\/p><\/td><\/tr><tr><td width=\"174\"><p>R\u00e9sistance \u00e0 l\u2019impact<\/p><\/td><td colspan=\"2\" width=\"222\"><p>Moyenne \u00e0 bonne<\/p><\/td><td colspan=\"2\" width=\"417\"><p>Bonne \u00e0 excellente<\/p><\/td><\/tr><tr><td width=\"174\"><p>R\u00e9sistance au feu<\/p><\/td><td colspan=\"2\" width=\"222\"><p>Faible<\/p><\/td><td colspan=\"2\" width=\"417\"><p>Tr\u00e8s bonne \u00e0 excellente<\/p><\/td><\/tr><tr><td width=\"174\"><p>\u00a0<\/p><\/td><td colspan=\"2\" width=\"222\"><p>\u00a0<\/p><\/td><td colspan=\"2\" width=\"417\"><p>\u00a0<\/p><\/td><\/tr><tr><td width=\"174\"><h3><strong>Caract\u00e9ristiques thermiques<\/strong><\/h3><\/td><td colspan=\"2\" width=\"222\"><h3><strong>Caoutchouc en nitrile<\/strong><\/h3><\/td><td colspan=\"2\" width=\"417\"><h3><strong>Caoutchouc en n\u00e9opr\u00e8ne<\/strong><\/h3><\/td><\/tr><tr><td width=\"174\"><p>Temp\u00e9rature de service minimale<\/p><\/td><td colspan=\"2\" width=\"222\"><p>De -30\u00b0F \u00e0 -70\u00b0F<\/p><\/td><td colspan=\"2\" width=\"417\"><p>De -30\u00b0F \u00e0 -70\u00b0F<\/p><\/td><\/tr><tr><td width=\"174\"><p>Temp\u00e9rature de service maximale<\/p><\/td><td colspan=\"2\" width=\"222\"><p>De +220\u00b0F \u00e0 +280\u00b0F<\/p><\/td><td colspan=\"2\" width=\"417\"><p>De +220\u00b0F \u00e0 +280\u00b0F<\/p><\/td><\/tr><tr><td width=\"174\"><p>\u00a0<\/p><\/td><td colspan=\"2\" width=\"222\"><p>\u00a0<\/p><\/td><td colspan=\"2\" width=\"417\"><p>\u00a0<\/p><\/td><\/tr><tr><td width=\"174\"><h3><strong>R\u00e9sistance environnementale<\/strong><\/h3><\/td><td colspan=\"2\" width=\"222\"><h3><strong>Caoutchouc en nitrile <\/strong><\/h3><\/td><td colspan=\"2\" width=\"417\"><h3><strong>Caoutchouc en n\u00e9opr\u00e8ne <\/strong><\/h3><\/td><\/tr><tr><td width=\"174\"><p>Intemp\u00e9ries<\/p><\/td><td colspan=\"2\" width=\"222\"><p>Faible<\/p><\/td><td colspan=\"2\" width=\"417\"><p>Bonne<\/p><\/td><\/tr><tr><td width=\"174\"><p>Rayons de soleil<\/p><\/td><td colspan=\"2\" width=\"222\"><p>Faible<\/p><\/td><td colspan=\"2\" width=\"417\"><p>De bonne \u00e0 tr\u00e8s bonne<\/p><\/td><\/tr><tr><td width=\"174\"><p>Ozone<\/p><\/td><td colspan=\"2\" width=\"222\"><p>Faible<\/p><\/td><td colspan=\"2\" width=\"417\"><p>Bonne<\/p><\/td><\/tr><tr><td width=\"174\"><p>Oxidation<\/p><\/td><td colspan=\"2\" width=\"222\"><p>Bonne<\/p><\/td><td colspan=\"2\" width=\"417\"><p>Bonne<\/p><\/td><\/tr><tr><td width=\"174\"><p>Eau<\/p><\/td><td colspan=\"2\" width=\"222\"><p>De bonne \u00e0 excellente<\/p><\/td><td colspan=\"2\" width=\"417\"><p>Excellente<\/p><\/td><\/tr><tr><td width=\"174\"><p>Vapeur<\/p><\/td><td colspan=\"2\" width=\"222\"><p>Moyenne<\/p><\/td><td colspan=\"2\" width=\"417\"><p>De faible \u00e0 bonne<\/p><\/td><\/tr><tr><td width=\"174\"><p>Perm\u00e9abilit\u00e9 gaz<\/p><\/td><td colspan=\"2\" width=\"222\"><p>De moyenne \u00e0 excellente<\/p><\/td><td colspan=\"2\" width=\"417\"><p>De moyenne \u00e0 bonne<\/p><\/td><\/tr><tr><td width=\"174\"><h3>\u00a0<\/h3><\/td><td colspan=\"2\" width=\"222\"><h3>\u00a0<\/h3><\/td><td colspan=\"2\" width=\"417\"><h3>\u00a0<\/h3><\/td><\/tr><tr><td width=\"174\"><h3><strong>R\u00e9sistance chimique<\/strong><\/h3><\/td><td colspan=\"2\" width=\"222\"><h3><strong>Caoutchouc en nitrile <\/strong><\/h3><\/td><td colspan=\"2\" width=\"417\"><h3><strong>Caoutchouc en n\u00e9opr<\/strong><strong>\u00e8<\/strong><strong>ne<\/strong><\/h3><\/td><\/tr><tr><td width=\"174\"><p>G\u00e9n\u00e9ralement r\u00e9sistants aux:<\/p><\/td><td colspan=\"2\" width=\"222\"><p>Gases, hydrocarbons aliphatiques, huiles et carburants<\/p><\/td><td colspan=\"2\" width=\"417\"><p>Produits chimiques et acides mod\u00e9r\u00e9s, ozone, huiles, graisses, lubrifiants et solvants<\/p><\/td><\/tr><tr><td width=\"174\"><p>G\u00e9n\u00e9ralement attaqu\u00e9s par:<\/p><\/td><td colspan=\"2\" width=\"222\"><p>C\u00e9tones, ozone, rayons de soleil, huiles aromatiques, feu, intemp\u00e9ries<\/p><\/td><td colspan=\"2\" width=\"417\"><p>Esters, c\u00e9tones, et par des hydrocarbures chlor\u00e9s, aromatiques et nitr\u00e9s<\/p><\/td><\/tr><tr><td width=\"174\">\u00a0<\/td><td width=\"97\">\u00a0<\/td><td width=\"125\">\u00a0<\/td><td width=\"146\">\u00a0<\/td><td width=\"271\">\u00a0<\/td><\/tr><\/tbody><\/table><h2><strong>Nitrile ou N\u00e9opr\u00e8ne: Applications<\/strong><\/h2><p>Le caoutchouc en nitrile est recommand\u00e9 pour les applications n\u00e9cessitant une r\u00e9sistance \u00e0 l&rsquo;huile et au carburants, \u00e0 l&rsquo;abrasion et aux temp\u00e9ratures jusqu&rsquo;\u00e0 280\u00b0F. Dans les \u00e9quipements mobiles et les v\u00e9hicules militaires, des sceaux ou des joints d&rsquo;\u00e9tanch\u00e9it\u00e9 en nitrile sont utilis\u00e9s dans les membranes de carburateurs, les circuits d&rsquo;alimentation en carburant et les flexibles hydrauliques. Le nitrile prend \u00e9galement en charge la liaison caoutchouc-m\u00e9tal, ce qui en fait un bon choix pour les applications de l&rsquo;industrie de transformation. Cependant, le nitrile n\u2019est pas recommand\u00e9 pour le scellement et l\u2019isolation n\u00e9cessitant une r\u00e9sistance au feu, aux rayons de soleil, \u00e0 l\u2019ozone ou aux intemp\u00e9ries.<\/p><p>Le caoutchouc en n\u00e9opr\u00e8ne r\u00e9siste au feu et aux rayons de soleil, \u00e0 l&rsquo;ozone et aux intemp\u00e9ries. Certains grades sp\u00e9cifiques de n\u00e9opr\u00e8ne peuvent \u00e9galement satisfaire aux exigences en mati\u00e8re de flammes, de fum\u00e9e et de toxicit\u00e9 (FireSmokeToxicity-FST) de l\u2019industrie du transport en commun. Les applications comprennent les joints de porte, les joints de fen\u00eatre, les couvre-tuyaux, les supports antivibratoires et les amortisseurs. Le n\u00e9opr\u00e8ne est \u00e9galement utilis\u00e9 avec les unit\u00e9s de CVC (Chauffage-Ventilation-Climatisation)-HVAC (Heating-Ventilation-Airconditioning), les bo\u00eetiers \u00e9lectriques ou \u00e9lectroniques et les coupe-froid pour les portes coupe-feu. Les applications suppl\u00e9mentaires incluent les joints de dilatation et les patins d&rsquo;appui dans les structures construites.<\/p><h2><strong>Nitrile ou n\u00e9opr\u00e8ne: faites le bon choix<\/strong><\/h2><p>La s\u00e9lection des compos\u00e9s est essentielle, car le choix du mauvais caoutchouc peut entra\u00eener bien plus qu&rsquo;une simple d\u00e9faillance au niveau des composants. Comparez-vous le nitrile au n\u00e9opr\u00e8ne pour votre application ? Avez-vous besoin de solutions d&rsquo;\u00e9tanch\u00e9it\u00e9 sur mesure qui ajoutent de la valeur et r\u00e9duisent les risques ? Alors, il est temps de parler \u00e0 Elasto Proxy. <a href=\"http:\/\/marketing.elastoproxy.com\/acton\/form\/15797\/0010:d-0001\/1\/-\/-\/-\/-\/index.htm\">Contactez-nous<\/a> pour parler de votre application.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8e64398 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8e64398\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1ae95d3\" data-id=\"1ae95d3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2b87bf7 elementor-widget elementor-widget-image\" data-id=\"2b87bf7\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"791\" src=\"https:\/\/www.elastoproxy.com\/wp-content\/uploads\/2019\/07\/Nitrile-vs.-Neoprene-1024x791.png\" class=\"attachment-large size-large wp-image-5252\" alt=\"Nitrile vs. Neoprene\" srcset=\"https:\/\/www.elastoproxy.com\/wp-content\/uploads\/2019\/07\/Nitrile-vs.-Neoprene-1024x791.png 1024w, https:\/\/www.elastoproxy.com\/wp-content\/uploads\/2019\/07\/Nitrile-vs.-Neoprene-300x232.png 300w, https:\/\/www.elastoproxy.com\/wp-content\/uploads\/2019\/07\/Nitrile-vs.-Neoprene-768x593.png 768w, https:\/\/www.elastoproxy.com\/wp-content\/uploads\/2019\/07\/Nitrile-vs.-Neoprene.png 1056w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Quelle est la diff\u00e9rence entre le nitrile et le n\u00e9opr\u00e8ne pour les sceaux, les joints d\u2019\u00e9tanch\u00e9it\u00e9 et les isolants ? Ces deux \u00e9lastom\u00e8res offrent une bonne r\u00e9sistance \u00e0 la compression r\u00e9manente et \u00e0 la d\u00e9chirure. Ils supportent \u00e9galement les m\u00eames temp\u00e9ratures de service. Certaines qualit\u00e9s de n\u00e9opr\u00e8ne offrent une excellente r\u00e9sistance \u00e0 l&rsquo;abrasion, mais le [&hellip;]<\/p>\n","protected":false},"author":20,"featured_media":5252,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ofc_enable_fullscreen":"disable","ofc_fullscreen_speed":0,"ofc_fullscreen_nav":"enable","ofc_fullscreen_nav_pos":"right","ofc_fullscreen_nav_color":"","ofc_fullscreen_nav_tooltip_color":"","ofc_fullscreen_responsive":0,"osh_disable_topbar_sticky":"default","osh_disable_header_sticky":"default","osh_sticky_header_style":"default","osh_sticky_header_effect":"","osh_custom_sticky_logo":0,"osh_custom_retina_sticky_logo":0,"osh_custom_sticky_logo_height":0,"osh_background_color":"","osh_links_color":"","osh_links_hover_color":"","osh_links_active_color":"","osh_links_bg_color":"","osh_links_hover_bg_color":"","osh_links_active_bg_color":"","osh_menu_social_links_color":"","osh_menu_social_hover_links_color":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"off","ocean_gallery_id":[],"footnotes":""},"categories":[15],"tags":[846,692,845,687,771,416,435],"class_list":["post-5258","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee","tag-jointsdetancheiteencaoutchouc","tag-jointsencaoutchouc","tag-joints-detancheite-en-caoutchouc","tag-joints-en-caoutchouc","tag-materiaux","tag-neoprene","tag-nitrile","entry","has-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Nitrile ou n\u00e9opr\u00e8ne | Joints en caoutchouc | Elasto Proxy<\/title>\n<meta name=\"description\" content=\"Le nitrile et le n\u00e9opr\u00e8ne ont de nombreuses similitudes mais aussi quelques diff\u00e9rences importantes. Comparez le nitrile au n\u00e9opr\u00e8ne.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.elastoproxy.com\/fr\/nitrile-ou-neoprene\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nitrile ou n\u00e9opr\u00e8ne | Joints en caoutchouc | Elasto Proxy\" \/>\n<meta property=\"og:description\" content=\"Le nitrile et le n\u00e9opr\u00e8ne ont de nombreuses similitudes mais aussi quelques diff\u00e9rences importantes. Comparez le nitrile au n\u00e9opr\u00e8ne.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.elastoproxy.com\/fr\/nitrile-ou-neoprene\/\" \/>\n<meta property=\"og:site_name\" content=\"Elasto Proxy\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-13T11:57:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-01T21:14:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.elastoproxy.com\/wp-content\/uploads\/2019\/07\/Nitrile-vs.-Neoprene.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1056\" \/>\n\t<meta property=\"og:image:height\" content=\"816\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Steve Melito\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Steve Melito\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nitrile ou n\u00e9opr\u00e8ne | Joints en caoutchouc | Elasto Proxy","description":"Le nitrile et le n\u00e9opr\u00e8ne ont de nombreuses similitudes mais aussi quelques diff\u00e9rences importantes. Comparez le nitrile au n\u00e9opr\u00e8ne.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.elastoproxy.com\/fr\/nitrile-ou-neoprene\/","og_locale":"fr_FR","og_type":"article","og_title":"Nitrile ou n\u00e9opr\u00e8ne | Joints en caoutchouc | Elasto Proxy","og_description":"Le nitrile et le n\u00e9opr\u00e8ne ont de nombreuses similitudes mais aussi quelques diff\u00e9rences importantes. Comparez le nitrile au n\u00e9opr\u00e8ne.","og_url":"https:\/\/www.elastoproxy.com\/fr\/nitrile-ou-neoprene\/","og_site_name":"Elasto Proxy","article_published_time":"2019-07-13T11:57:51+00:00","article_modified_time":"2021-03-01T21:14:42+00:00","og_image":[{"width":1056,"height":816,"url":"https:\/\/www.elastoproxy.com\/wp-content\/uploads\/2019\/07\/Nitrile-vs.-Neoprene.png","type":"image\/png"}],"author":"Steve Melito","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Steve Melito","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.elastoproxy.com\/fr\/nitrile-ou-neoprene\/#article","isPartOf":{"@id":"https:\/\/www.elastoproxy.com\/fr\/nitrile-ou-neoprene\/"},"author":{"name":"Steve Melito","@id":"https:\/\/www.elastoproxy.com\/#\/schema\/person\/54c278304f2b3726bb8de1bb1b5df225"},"headline":"Nitrile ou n\u00e9opr\u00e8ne, pour sceaux, joints d&rsquo;\u00e9tanch\u00e9it\u00e9 et isolants en caoutchouc","datePublished":"2019-07-13T11:57:51+00:00","dateModified":"2021-03-01T21:14:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.elastoproxy.com\/fr\/nitrile-ou-neoprene\/"},"wordCount":990,"commentCount":0,"publisher":{"@id":"https:\/\/www.elastoproxy.com\/#organization"},"image":{"@id":"https:\/\/www.elastoproxy.com\/fr\/nitrile-ou-neoprene\/#primaryimage"},"thumbnailUrl":"https:\/\/www.elastoproxy.com\/wp-content\/uploads\/2019\/07\/Nitrile-vs.-Neoprene.png","keywords":["#Jointsd'\u00e9tanch\u00e9it\u00e9enCaoutchouc","#Jointsencaoutchouc","joints d'\u00e9tanch\u00e9it\u00e9 en caoutchouc","joints en caoutchouc","mat\u00e9riaux","neoprene","nitrile"],"articleSection":["Non classifi\u00e9(e)"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.elastoproxy.com\/fr\/nitrile-ou-neoprene\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.elastoproxy.com\/fr\/nitrile-ou-neoprene\/","url":"https:\/\/www.elastoproxy.com\/fr\/nitrile-ou-neoprene\/","name":"Nitrile ou n\u00e9opr\u00e8ne | Joints en caoutchouc | Elasto Proxy","isPartOf":{"@id":"https:\/\/www.elastoproxy.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.elastoproxy.com\/fr\/nitrile-ou-neoprene\/#primaryimage"},"image":{"@id":"https:\/\/www.elastoproxy.com\/fr\/nitrile-ou-neoprene\/#primaryimage"},"thumbnailUrl":"https:\/\/www.elastoproxy.com\/wp-content\/uploads\/2019\/07\/Nitrile-vs.-Neoprene.png","datePublished":"2019-07-13T11:57:51+00:00","dateModified":"2021-03-01T21:14:42+00:00","description":"Le nitrile et le n\u00e9opr\u00e8ne ont de nombreuses similitudes mais aussi quelques diff\u00e9rences importantes. Comparez le nitrile au n\u00e9opr\u00e8ne.","breadcrumb":{"@id":"https:\/\/www.elastoproxy.com\/fr\/nitrile-ou-neoprene\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.elastoproxy.com\/fr\/nitrile-ou-neoprene\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.elastoproxy.com\/fr\/nitrile-ou-neoprene\/#primaryimage","url":"https:\/\/www.elastoproxy.com\/wp-content\/uploads\/2019\/07\/Nitrile-vs.-Neoprene.png","contentUrl":"https:\/\/www.elastoproxy.com\/wp-content\/uploads\/2019\/07\/Nitrile-vs.-Neoprene.png","width":1056,"height":816,"caption":"Nitrile vs. Neoprene"},{"@type":"BreadcrumbList","@id":"https:\/\/www.elastoproxy.com\/fr\/nitrile-ou-neoprene\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.elastoproxy.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Nitrile ou n\u00e9opr\u00e8ne, pour sceaux, joints d&rsquo;\u00e9tanch\u00e9it\u00e9 et isolants en caoutchouc"}]},{"@type":"WebSite","@id":"https:\/\/www.elastoproxy.com\/#website","url":"https:\/\/www.elastoproxy.com\/","name":"Elasto Proxy","description":"Rubber Fabricator and Distributor","publisher":{"@id":"https:\/\/www.elastoproxy.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.elastoproxy.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.elastoproxy.com\/#organization","name":"Elasto Proxy","url":"https:\/\/www.elastoproxy.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.elastoproxy.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.elastoproxy.com\/wp-content\/uploads\/2018\/10\/logo-elastoproxy.png","contentUrl":"https:\/\/www.elastoproxy.com\/wp-content\/uploads\/2018\/10\/logo-elastoproxy.png","width":200,"height":61,"caption":"Elasto Proxy"},"image":{"@id":"https:\/\/www.elastoproxy.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.elastoproxy.com\/#\/schema\/person\/54c278304f2b3726bb8de1bb1b5df225","name":"Steve Melito","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.elastoproxy.com\/#\/schema\/person\/image\/","url":"https:\/\/www.elastoproxy.com\/wp-content\/litespeed\/avatar\/cf7233bebd28fab336564db23356c33b.jpg?ver=1784028787","contentUrl":"https:\/\/www.elastoproxy.com\/wp-content\/litespeed\/avatar\/cf7233bebd28fab336564db23356c33b.jpg?ver=1784028787","caption":"Steve Melito"},"url":"https:\/\/www.elastoproxy.com\/fr\/author\/smelito\/"}]}},"_links":{"self":[{"href":"https:\/\/www.elastoproxy.com\/fr\/wp-json\/wp\/v2\/posts\/5258","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elastoproxy.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.elastoproxy.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.elastoproxy.com\/fr\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elastoproxy.com\/fr\/wp-json\/wp\/v2\/comments?post=5258"}],"version-history":[{"count":7,"href":"https:\/\/www.elastoproxy.com\/fr\/wp-json\/wp\/v2\/posts\/5258\/revisions"}],"predecessor-version":[{"id":12868,"href":"https:\/\/www.elastoproxy.com\/fr\/wp-json\/wp\/v2\/posts\/5258\/revisions\/12868"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.elastoproxy.com\/fr\/wp-json\/wp\/v2\/media\/5252"}],"wp:attachment":[{"href":"https:\/\/www.elastoproxy.com\/fr\/wp-json\/wp\/v2\/media?parent=5258"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.elastoproxy.com\/fr\/wp-json\/wp\/v2\/categories?post=5258"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.elastoproxy.com\/fr\/wp-json\/wp\/v2\/tags?post=5258"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}