{"id":4954,"date":"2019-04-27T08:38:14","date_gmt":"2019-04-27T12:38:14","guid":{"rendered":"https:\/\/www.elastoproxy.com\/?p=4954"},"modified":"2021-03-01T16:14:40","modified_gmt":"2021-03-01T21:14:40","slug":"joints-de-boitiers-electriques","status":"publish","type":"post","link":"https:\/\/www.elastoproxy.com\/fr\/joints-de-boitiers-electriques\/","title":{"rendered":"Joints de bo\u00eetiers \u00e9lectriques et joints de groupes \u00e9lectrog\u00e8nes"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"4954\" class=\"elementor elementor-4954 elementor-bc-flex-widget\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-79560ed elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"79560ed\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1378698\" data-id=\"1378698\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-85439fd elementor-widget elementor-widget-text-editor\" data-id=\"85439fd\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les joints d&rsquo;\u00e9tanch\u00e9it\u00e9 de bo\u00eetier \u00e9lectrique sont des produits industriels en caoutchouc qui assurent l&rsquo;\u00e9tanch\u00e9it\u00e9, l&rsquo;isolation et la protection de l&rsquo;environnement. Ils sont install\u00e9s \u00e0 l\u2019int\u00e9rieur de bo\u00eetiers de type armoire contenant des machines ou des \u00e9quipements \u00e9lectriques tels que des groupes \u00e9lectrog\u00e8nes. En plus de la protection contre les intemp\u00e9ries, les joints d&rsquo;\u00e9tanch\u00e9it\u00e9 des bo\u00eetiers \u00e9lectriques, tels que les joints d&rsquo;\u00e9tanch\u00e9it\u00e9 en caoutchouc pour groupes \u00e9lectrog\u00e8nes, peuvent conf\u00e9rer des propri\u00e9t\u00e9s sp\u00e9cialis\u00e9es telles que la r\u00e9sistance aux flammes ou aux produits chimiques et\u00a0 m\u00eame le blindage EMI. Ils peuvent \u00e9galement aider les ing\u00e9nieurs \u00e0 respecter les normes IP, la classification NEMA ou les exigences UL 94.<\/p><h2><strong>L<\/strong><strong>\u2019<\/strong><strong>\u00c9tanch\u00e9it\u00e9 du bo\u00eetier et le contr\u00f4le du bruit<\/strong><\/h2><p>Les groupes \u00e9lectrog\u00e8nes fournissent de l&rsquo;\u00e9lectricit\u00e9 hors r\u00e9seau. Ils se composent d\u2019un moteur diesel ou \u00e0 essence et d\u2019un g\u00e9n\u00e9rateur \u00e9lectrique qui convertit l\u2019\u00e9nergie m\u00e9canique en \u00e9lectricit\u00e9. Pour faciliter les r\u00e9parations et la maintenance cet \u00e9quipement est log\u00e9 dans un bo\u00eetier en m\u00e9tal ou en plastique avec une porte ou un couvercle amovible. Les joints de porte en caoutchouc peuvent fournir une \u00e9tanch\u00e9it\u00e9 environnementale fiable, mais vous devrez peut-\u00eatre aussi contr\u00f4ler le bruit du groupe \u00e9lectrog\u00e8ne.<\/p><p>Les joints d&rsquo;\u00e9tanch\u00e9it\u00e9 des bo\u00eetiers \u00e9lectriques procurent une certaine isolation acoustique, mais un moteur dans un espace clos peut \u00eatre tr\u00e8s bruyant. Parall\u00e8lement aux joints de porte du groupe \u00e9lectrog\u00e8ne, votre application peut n\u00e9cessiter des absorbants acoustiques, des <a href=\"https:\/\/www.elastoproxy.com\/noise-barriers\/\">\u00e9crans antibruit<\/a> ou m\u00eame des amortisseurs de vibrations en caoutchouc et d\u2019autres mat\u00e9riaux. Ces produits de contr\u00f4le du bruit peuvent vous aider \u00e0 respecter les limites d&rsquo;exposition au bruit sur le lieu de travail et \u00e0 \u00e9viter les \u00ab\u00a0nuisances sonores\u00a0\u00bb dans les quartiers.<\/p><p>Assurer l\u2019\u00e9tanch\u00e9it\u00e9 de l\u2019environnement peut sembler plus simple, mais il reste encore beaucoup \u00e0 consid\u00e9rer. Les joints statiques conviennent parfaitement lorsqu&rsquo;il n&rsquo;y a pas de mouvement relatif entre les surfaces de contact, mais des joints dynamiques sont recommand\u00e9s lorsqu&rsquo;il y a un mouvement entre les interfaces d&rsquo;\u00e9tanch\u00e9it\u00e9 telles qu&rsquo;une porte et un cadre de porte. Les joints en caoutchouc doivent \u00e9galement r\u00e9sister \u00e0 la compression &#8211; la d\u00e9formation permanente d&rsquo;un mat\u00e9riau &#8211; lorsque la porte du bo\u00eetier est ferm\u00e9e.<\/p><h2><strong>NEMA, IP et UL 94<\/strong><\/h2><p>Les normes NEMA et les cotes IP pour les bo\u00eetiers \u00e9lectriques sont similaires, mais ils ne sont certainement pas les m\u00eames. Les indices de protection contre la p\u00e9n\u00e9tration (IP) d\u00e9crivent le niveau de protection contre l&rsquo;entr\u00e9e ou la p\u00e9n\u00e9tration d&rsquo;eau et d&rsquo;objets solides tels que des particules de salet\u00e9 et de poussi\u00e8re. La National Electrical Manufacturers Association (NEMA) <a href=\"https:\/\/www.nema.org\/products\/documents\/nema-enclosure-types.pdf\">publie des normes<\/a> offrant une protection suppl\u00e9mentaire, notamment contre la corrosion et les produits chimiques.<\/p><p>Certaines conceptions de bo\u00eetiers peuvent n\u00e9cessiter des joints en caoutchouc r\u00e9sistant au feu. <a href=\"https:\/\/www.elastoproxy.com\/ul-gasket-materials-ul94-ul50e\/\">La norme UL 94<\/a> de Underwriters Laboratories (UL) d\u00e9finit 12 indices de flamme diff\u00e9rents. Il est donc important de d\u00e9terminer laquelle s\u2019applique au joint de votre bo\u00eetier \u00e9lectrique. Il est \u00e9galement important de d\u00e9terminer si le joint du g\u00e9n\u00e9rateur ou l\u2019ensemble du bo\u00eetier doivent satisfaire \u00e0 cette norme d\u2019inflammabilit\u00e9 \u00e9lev\u00e9e.<\/p><h2><strong>Le blindage EMI<\/strong><\/h2><p>Les joints d&rsquo;\u00e9tanch\u00e9it\u00e9 du bo\u00eetier \u00e9lectrique peuvent n\u00e9cessiter une protection contre les interf\u00e9rences \u00e9lectromagn\u00e9tiques (IEM), i.e., des perturbations \u00e9lectriques pouvant perturber ou endommager les circuits sensibles. Les causes des IEM sont nombreuses et peuvent inclure des sources d&rsquo;origine humaine ou naturelle. Dans les contextes industriels et commerciaux, les causes des perturbations \u00e9lectromagn\u00e9tiques sont g\u00e9n\u00e9ralement les moteurs \u00e0 balais, les circuits informatiques et l\u2019\u00e9clairage.<\/p><p>Les joints de bo\u00eetier en silicone remplis de particules assurent \u00e0 la fois une protection contre les interf\u00e9rences \u00e9lectromagn\u00e9tiques et une \u00e9tanch\u00e9it\u00e9 environnementale. Les \u00e9lastom\u00e8res \u00e0 base de m\u00e9tal fournissent \u00e9galement une conductivit\u00e9 \u00e9lectrique et r\u00e9sistent \u00e0 une large gamme de temp\u00e9ratures de service. Pour les applications n\u00e9cessitant une r\u00e9sistance aux carburants et aux fluides industriels, des joints IEM en fluorosilicones remplis de particules sont utilis\u00e9s.<\/p><h2><strong>Trouver des joints d&rsquo;\u00e9tanch\u00e9it\u00e9 de bo\u00eetier et des joints d&rsquo;\u00e9tanch\u00e9it\u00e9 en caoutchouc<\/strong><\/h2><p>Elasto Proxy fabrique des joints d&rsquo;\u00e9tanch\u00e9it\u00e9 pour les bo\u00eetiers \u00e9lectriques et en caoutchouc des groupes \u00e9lectrog\u00e8nes. Nous achetons des mat\u00e9riaux en caoutchouc sous forme de feuilles, de rouleaux et de profil\u00e9s et nous nous sp\u00e9cialisons dans la fabrication de joints de faibles \u00e0 moyennes dimensions pour des quantit\u00e9s de commande minimales (MOQ) int\u00e9ressantes. Avec notre \u00e9quipement de d\u00e9coupe au jet d&rsquo;eau, nous pouvons effectuer des coupes fines et rapides sans attendre l&rsquo;outillage. Nous proposons \u00e9galement diverses m\u00e9thodes de collage pour des joints de porte en caoutchouc fiables.<\/p><p>En tant que fabricant \u00e0 valeur ajout\u00e9e Elasto Proxy peut aussi examiner les conceptions de vos joints d&rsquo;\u00e9tanch\u00e9it\u00e9 du bo\u00eetier et m\u00eame faire des recommandations de r\u00e9duction des co\u00fbts pour les compos\u00e9s de caoutchouc. Parfois, les ing\u00e9nieurs pensent avoir besoin d&rsquo;un caoutchouc sp\u00e9cial lorsqu&rsquo;un \u00e9lastom\u00e8re de base pourrait r\u00e9pondre aux exigences de l&rsquo;application. Pour en savoir plus sur les joints d&rsquo;\u00e9tanch\u00e9it\u00e9 des bo\u00eetiers \u00e9lectriques ou des joints de groupes \u00e9lectrog\u00e8nes en caoutchouc, <a href=\"http:\/\/marketing.elastoproxy.com\/acton\/form\/15797\/0010:d-0001\/1\/-\/-\/-\/-\/index.htm\">contactez-nous<\/a>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Les joints d&rsquo;\u00e9tanch\u00e9it\u00e9 de bo\u00eetier \u00e9lectrique sont des produits industriels en caoutchouc qui assurent l&rsquo;\u00e9tanch\u00e9it\u00e9, l&rsquo;isolation et la protection de l&rsquo;environnement. Ils sont install\u00e9s \u00e0 l\u2019int\u00e9rieur de bo\u00eetiers de type armoire contenant des machines ou des \u00e9quipements \u00e9lectriques tels que des groupes \u00e9lectrog\u00e8nes. En plus de la protection contre les intemp\u00e9ries, les joints d&rsquo;\u00e9tanch\u00e9it\u00e9 des [&hellip;]<\/p>\n","protected":false},"author":20,"featured_media":4932,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ofc_enable_fullscreen":"disable","ofc_fullscreen_speed":0,"ofc_fullscreen_nav":"enable","ofc_fullscreen_nav_pos":"right","ofc_fullscreen_nav_color":"","ofc_fullscreen_nav_tooltip_color":"","ofc_fullscreen_responsive":0,"osh_disable_topbar_sticky":"default","osh_disable_header_sticky":"default","osh_sticky_header_style":"default","osh_sticky_header_effect":"","osh_custom_sticky_logo":0,"osh_custom_retina_sticky_logo":0,"osh_custom_sticky_logo_height":0,"osh_background_color":"","osh_links_color":"","osh_links_hover_color":"","osh_links_active_color":"","osh_links_bg_color":"","osh_links_hover_bg_color":"","osh_links_active_bg_color":"","osh_menu_social_links_color":"","osh_menu_social_hover_links_color":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"off","ocean_gallery_id":[],"footnotes":""},"categories":[15],"tags":[550,739,738,740,741,715,735,734,736,737,714,401],"class_list":["post-4954","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee","tag-elastoproxy","tag-jointsdeboitier","tag-jointsdeboitierelectrique","tag-jointsdegroupeselectrogenes","tag-jointsdeporte","tag-ip","tag-joint-de-boitier","tag-joints-de-boitier-electrique","tag-joints-de-groupes-electrogenes","tag-joints-de-porte","tag-nema","tag-ul-94","entry","has-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Joints de Bo\u00eetiers \u00e9lectriques | Joints de Groupes \u00e9lectrog\u00e8nes<\/title>\n<meta name=\"description\" content=\"Les joints du bo\u00eetier \u00e9lectrique donnent de l&#039;\u00e9tanch\u00e9it\u00e9, de l&#039;isolation et de la protection. Ils comprennent des joints en caoutchouc pour groupes \u00e9lectrog\u00e8nes et peuvent aider \u00e0 satisfaire aux normes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.elastoproxy.com\/fr\/joints-de-boitiers-electriques\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Joints de Bo\u00eetiers \u00e9lectriques | Joints de Groupes \u00e9lectrog\u00e8nes\" \/>\n<meta property=\"og:description\" content=\"Les joints du bo\u00eetier \u00e9lectrique donnent de l&#039;\u00e9tanch\u00e9it\u00e9, de l&#039;isolation et de la protection. Ils comprennent des joints en caoutchouc pour groupes \u00e9lectrog\u00e8nes et peuvent aider \u00e0 satisfaire aux normes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.elastoproxy.com\/fr\/joints-de-boitiers-electriques\/\" \/>\n<meta property=\"og:site_name\" content=\"Elasto Proxy\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-27T12:38:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-01T21:14:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.elastoproxy.com\/wp-content\/uploads\/2019\/04\/Electrical-Enclosure-Gaskets.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"463\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Steve Melito\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Steve Melito\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Joints de Bo\u00eetiers \u00e9lectriques | Joints de Groupes \u00e9lectrog\u00e8nes","description":"Les joints du bo\u00eetier \u00e9lectrique donnent de l'\u00e9tanch\u00e9it\u00e9, de l'isolation et de la protection. Ils comprennent des joints en caoutchouc pour groupes \u00e9lectrog\u00e8nes et peuvent aider \u00e0 satisfaire aux normes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.elastoproxy.com\/fr\/joints-de-boitiers-electriques\/","og_locale":"fr_FR","og_type":"article","og_title":"Joints de Bo\u00eetiers \u00e9lectriques | Joints de Groupes \u00e9lectrog\u00e8nes","og_description":"Les joints du bo\u00eetier \u00e9lectrique donnent de l'\u00e9tanch\u00e9it\u00e9, de l'isolation et de la protection. Ils comprennent des joints en caoutchouc pour groupes \u00e9lectrog\u00e8nes et peuvent aider \u00e0 satisfaire aux normes.","og_url":"https:\/\/www.elastoproxy.com\/fr\/joints-de-boitiers-electriques\/","og_site_name":"Elasto Proxy","article_published_time":"2019-04-27T12:38:14+00:00","article_modified_time":"2021-03-01T21:14:40+00:00","og_image":[{"width":640,"height":463,"url":"https:\/\/www.elastoproxy.com\/wp-content\/uploads\/2019\/04\/Electrical-Enclosure-Gaskets.jpg","type":"image\/jpeg"}],"author":"Steve Melito","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Steve Melito","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.elastoproxy.com\/fr\/joints-de-boitiers-electriques\/#article","isPartOf":{"@id":"https:\/\/www.elastoproxy.com\/fr\/joints-de-boitiers-electriques\/"},"author":{"name":"Steve Melito","@id":"https:\/\/www.elastoproxy.com\/#\/schema\/person\/54c278304f2b3726bb8de1bb1b5df225"},"headline":"Joints de bo\u00eetiers \u00e9lectriques et joints de groupes \u00e9lectrog\u00e8nes","datePublished":"2019-04-27T12:38:14+00:00","dateModified":"2021-03-01T21:14:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.elastoproxy.com\/fr\/joints-de-boitiers-electriques\/"},"wordCount":952,"commentCount":0,"publisher":{"@id":"https:\/\/www.elastoproxy.com\/#organization"},"image":{"@id":"https:\/\/www.elastoproxy.com\/fr\/joints-de-boitiers-electriques\/#primaryimage"},"thumbnailUrl":"https:\/\/www.elastoproxy.com\/wp-content\/uploads\/2019\/04\/Electrical-Enclosure-Gaskets.jpg","keywords":["#ElastoProxy","#JointsdeBo\u00eetier","#JointsdeBo\u00eetier\u00c9lectrique","#Jointsdegroupes\u00e9lectrog\u00e8nes","#JointsdePorte","IP","joint de bo\u00eetier","joints de bo\u00eetier \u00e9lectrique","joints de groupes \u00e9lectrog\u00e8nes","joints de porte","NEMA","UL 94"],"articleSection":["Non classifi\u00e9(e)"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.elastoproxy.com\/fr\/joints-de-boitiers-electriques\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.elastoproxy.com\/fr\/joints-de-boitiers-electriques\/","url":"https:\/\/www.elastoproxy.com\/fr\/joints-de-boitiers-electriques\/","name":"Joints de Bo\u00eetiers \u00e9lectriques | Joints de Groupes \u00e9lectrog\u00e8nes","isPartOf":{"@id":"https:\/\/www.elastoproxy.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.elastoproxy.com\/fr\/joints-de-boitiers-electriques\/#primaryimage"},"image":{"@id":"https:\/\/www.elastoproxy.com\/fr\/joints-de-boitiers-electriques\/#primaryimage"},"thumbnailUrl":"https:\/\/www.elastoproxy.com\/wp-content\/uploads\/2019\/04\/Electrical-Enclosure-Gaskets.jpg","datePublished":"2019-04-27T12:38:14+00:00","dateModified":"2021-03-01T21:14:40+00:00","description":"Les joints du bo\u00eetier \u00e9lectrique donnent de l'\u00e9tanch\u00e9it\u00e9, de l'isolation et de la protection. Ils comprennent des joints en caoutchouc pour groupes \u00e9lectrog\u00e8nes et peuvent aider \u00e0 satisfaire aux normes.","breadcrumb":{"@id":"https:\/\/www.elastoproxy.com\/fr\/joints-de-boitiers-electriques\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.elastoproxy.com\/fr\/joints-de-boitiers-electriques\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.elastoproxy.com\/fr\/joints-de-boitiers-electriques\/#primaryimage","url":"https:\/\/www.elastoproxy.com\/wp-content\/uploads\/2019\/04\/Electrical-Enclosure-Gaskets.jpg","contentUrl":"https:\/\/www.elastoproxy.com\/wp-content\/uploads\/2019\/04\/Electrical-Enclosure-Gaskets.jpg","width":640,"height":463,"caption":"Electrical Enclosure Gaskets | joints de bo\u00eetiers \u00e9lectriques"},{"@type":"BreadcrumbList","@id":"https:\/\/www.elastoproxy.com\/fr\/joints-de-boitiers-electriques\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.elastoproxy.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Joints de bo\u00eetiers \u00e9lectriques et joints de groupes \u00e9lectrog\u00e8nes"}]},{"@type":"WebSite","@id":"https:\/\/www.elastoproxy.com\/#website","url":"https:\/\/www.elastoproxy.com\/","name":"Elasto Proxy","description":"Rubber Fabricator and Distributor","publisher":{"@id":"https:\/\/www.elastoproxy.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.elastoproxy.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.elastoproxy.com\/#organization","name":"Elasto Proxy","url":"https:\/\/www.elastoproxy.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.elastoproxy.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.elastoproxy.com\/wp-content\/uploads\/2018\/10\/logo-elastoproxy.png","contentUrl":"https:\/\/www.elastoproxy.com\/wp-content\/uploads\/2018\/10\/logo-elastoproxy.png","width":200,"height":61,"caption":"Elasto Proxy"},"image":{"@id":"https:\/\/www.elastoproxy.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.elastoproxy.com\/#\/schema\/person\/54c278304f2b3726bb8de1bb1b5df225","name":"Steve Melito","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.elastoproxy.com\/#\/schema\/person\/image\/","url":"https:\/\/www.elastoproxy.com\/wp-content\/litespeed\/avatar\/cf7233bebd28fab336564db23356c33b.jpg?ver=1788262653","contentUrl":"https:\/\/www.elastoproxy.com\/wp-content\/litespeed\/avatar\/cf7233bebd28fab336564db23356c33b.jpg?ver=1788262653","caption":"Steve Melito"},"url":"https:\/\/www.elastoproxy.com\/fr\/author\/smelito\/"}]}},"_links":{"self":[{"href":"https:\/\/www.elastoproxy.com\/fr\/wp-json\/wp\/v2\/posts\/4954","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elastoproxy.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.elastoproxy.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.elastoproxy.com\/fr\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elastoproxy.com\/fr\/wp-json\/wp\/v2\/comments?post=4954"}],"version-history":[{"count":6,"href":"https:\/\/www.elastoproxy.com\/fr\/wp-json\/wp\/v2\/posts\/4954\/revisions"}],"predecessor-version":[{"id":12858,"href":"https:\/\/www.elastoproxy.com\/fr\/wp-json\/wp\/v2\/posts\/4954\/revisions\/12858"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.elastoproxy.com\/fr\/wp-json\/wp\/v2\/media\/4932"}],"wp:attachment":[{"href":"https:\/\/www.elastoproxy.com\/fr\/wp-json\/wp\/v2\/media?parent=4954"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.elastoproxy.com\/fr\/wp-json\/wp\/v2\/categories?post=4954"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.elastoproxy.com\/fr\/wp-json\/wp\/v2\/tags?post=4954"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}