{"id":4782,"date":"2019-03-16T14:23:31","date_gmt":"2019-03-16T18:23:31","guid":{"rendered":"https:\/\/www.elastoproxy.com\/?p=4782"},"modified":"2019-03-16T14:24:46","modified_gmt":"2019-03-16T18:24:46","slug":"voici-elizabeth-shively","status":"publish","type":"post","link":"https:\/\/www.elastoproxy.com\/fr\/voici-elizabeth-shively\/","title":{"rendered":"Profiles d\u2019Elasto Proxy: voici Elizabeth Shively"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"4782\" class=\"elementor elementor-4782 elementor-bc-flex-widget\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-87f699f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"87f699f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-dcc606b\" data-id=\"dcc606b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-90d85f9 elementor-widget elementor-widget-text-editor\" data-id=\"90d85f9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Elizabeth Shively est repr\u00e9sentante des ventes pour Elasto Proxy au si\u00e8ge social de la compagnie \u00e0 Boisbriand, Qu\u00e9bec, Canada. Originaire de Raymond, dans le Maine, aux \u00c9tats-Unis, elle a grandi dans une petite ville au bord du lac Sebago avant de s\u2019en aller vers le sud pour obtenir un dipl\u00f4me d&rsquo;ing\u00e9nieur en quatre ans \u00e0 la North Carolina State University. Certains \u00e9tudiants rentrent chez eux apr\u00e8s avoir obtenu leur dipl\u00f4me, tandis que d&rsquo;autres vont dans des lieux familiers. Pour Elizabeth Shively, la vie apr\u00e8s l\u2019obtention de son dipl\u00f4me signifiait choisir un chemin diff\u00e9rent, plus nordique en fait.<\/p><p>Durant son s\u00e9jour \u00e0 l&rsquo;universit\u00e9 Elizabeth Shively a en effet rencontr\u00e9 son futur mari, un citoyen canadien vivant au Qu\u00e9bec, o\u00f9 le fran\u00e7ais est la langue officielle. Quand elle a d\u00e9m\u00e9nag\u00e9 au Canada, elle ne pouvait initialement ni travailler ni aller \u00e0 l&rsquo;\u00e9cole pendant le traitement de ses documents d&rsquo;immigration. Au cours de ces huit mois d\u2019attente elle s&rsquo;est donc immerg\u00e9e dans des conversations \u00e9l\u00e9mentaires avec des ami(e)s qui ne parlaient que le fran\u00e7ais avec elle. Elizabeth avait d\u00e9j\u00e0 suivi quelques cours de fran\u00e7ais \u00e0 l&rsquo;universit\u00e9 bien entendu, ce qui lui avait donn\u00e9 une bonne base en grammaire.<\/p><p>Quand finalement elle a obtenu le droit de travailler au Qu\u00e9bec Elizabeth Shively a trouv\u00e9 d\u2019abord un emploi dans un magasin de sport pour am\u00e9liorer ses comp\u00e9tences linguistiques en fran\u00e7ais. Puis, elle a commenc\u00e9 \u00e0 chercher des postes d&rsquo;ing\u00e9nieur. Lorsqu&rsquo;elle a vu un jour, sur LinkedIn, une annonce d&rsquo;Elasto Proxy, elle a utilis\u00e9 son profil sur LinkedIn pour postuler. Elle s\u2019int\u00e9ressait aux atouts de la compagnie d&rsquo;autant plus qu&rsquo;Elasto Proxy est sp\u00e9cialis\u00e9e dans la fabrication sur mesure plut\u00f4t que dans la vente par catalogue. Au cours de son entrevue, elle est <em>\u00ab tomb\u00e9e amoureuse \u00bb<\/em> de la compagnie en raison de la motivation, du travail d\u2019\u00e9quipe et de l\u2019orientation envers le client qui existent chez Elasto Proxy.<\/p><p>\u00ab En tant que repr\u00e9sentante des ventes je dois avoir confiance et aimer ce que je vends \u00bb, explique Elizabeth Shively. \u00ab Les gens ici sont vraiment passionn\u00e9s par les produits et leur qualit\u00e9. C\u2019est le genre de choses que j&rsquo;aime bien ! \u00bb Aujourd&rsquo;hui, presque deux ans apr\u00e8s avoir rejoint Elasto Proxy, elle travaille sur un territoire de vente qui comprend le Qu\u00e9bec, certaines parties de l\u2019Outaouais et le nord-est des \u00c9tats-Unis. La plupart de ses clients parlent anglais, mais pas moins de 40% parlent fran\u00e7ais ! Lorsqu&rsquo;elle est au bureau de Boisbriand avec ses coll\u00e8gues, environ 40% des conversations se font donc en fran\u00e7ais aussi.<\/p><h2><strong>Le fran\u00e7ais et l&rsquo;ing\u00e9nierie<\/strong><\/h2><p>Ma\u00eetriser une nouvelle langue est tout un d\u00e9fi, mais l&rsquo;obtention d&rsquo;un dipl\u00f4me d&rsquo;ing\u00e9nieur de quatre ans l&rsquo;est \u00e9galement ! Gr\u00e2ce \u00e0 son \u00e9ducation, Elizabeth Shively peut toutefois comprendre comment les ing\u00e9nieurs r\u00e9solvent des probl\u00e8mes et prennent des d\u00e9cisions. \u00ab Ils veulent comprendre comment tout fonctionne \u00bb, explique-t-elle. Ce processus consiste en partie \u00e0 r\u00e9pondre \u00e0 des questions sur l&rsquo;impact du choix d&rsquo;un mat\u00e9riau de joint sur la conception globale d&rsquo;un produit. Deux types de caoutchouc diff\u00e9rents peuvent fonctionner tous les deux, mais il faut donc trouver un \u00e9quilibre entre prix et performance.<\/p><p>La plupart des ing\u00e9nieurs avec lesquels Elizabeth Shively parle sont habitu\u00e9s \u00e0 travailler avec du m\u00e9tal. Ils savent qu\u2019ils ne peuvent pas simplement remplacer l\u2019acier inoxydable par de l\u2019aluminium, mais il est parfois possible de remplacer un caoutchouc plus co\u00fbteux par un compos\u00e9 moins co\u00fbteux. Les ing\u00e9nieurs qui travaillent avec des pi\u00e8ces m\u00e9talliques peuvent ne pas savoir que les tol\u00e9rances ou r\u00e9sistances des pi\u00e8ces en caoutchouc sont \u00e9galement diff\u00e9rentes. Elizabeth Shively a aussi beaucoup appris. \u00ab Ce n\u2019est pas toujours noir et blanc comme dans l\u2019ing\u00e9nierie \u00bb, dit-elle. \u00ab Vous devez apprendre le c\u00f4t\u00e9 communication des choses. \u00bb<\/p><p>Parfois, communiquer avec des clients potentiels peut impliquer d\u2019\u00eatre pris comme un \u00ab <em>punching bag<\/em> &#8211; <em>sac de boxe<\/em> \u00bb en quelque sorte, m\u00eame lorsque la frustration d\u2019un ing\u00e9nieur provient d\u2019une pi\u00e8ce ou d\u2019un produit fabriqu\u00e9 par une autre personne. \u00ab Nous recherchons des solutions aux probl\u00e8mes \u00bb, explique-t-elle. Elasto Proxy prend donc le temps de bien comprendre les probl\u00e8mes. Elizabeth Shively a aussi appris qu\u2019il existe diff\u00e9rents types de \u00ab non \u00bb dans les situations de vente. \u00ab\u00a0 D\u00e9couvrez pourquoi le \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00ab non \u00bb est un \u00ab non \u00bb et s\u2019il existe une meilleure solution \u00bb, conseille-t-elle.<\/p><p>Tout en perfectionnant ses comp\u00e9tences en vente, Elizabeth Shively cherche \u00e0 d\u00e9velopper l\u2019activit\u00e9 commerciale d\u2019Elasto Proxy dans le nord-est des \u00c9tats-Unis. Une partie de sa strat\u00e9gie consiste \u00e0 participer \u00e0 des salons professionnels, y compris des \u00e9v\u00e9nements pour l\u2019industrie des dispositifs m\u00e9dicaux. Elasto Proxy est particuli\u00e8rement forte dans les domaines de l\u2019\u00e9quipement mobile et de la d\u00e9fense. Elle est donc \u00e9galement int\u00e9ress\u00e9e par les possibilit\u00e9s qui s\u2019offrent \u00e0 elle. Elle passe environ une journ\u00e9e sur la route chaque semaine, y compris les visites aux clients, et elle aime partager ce qu&rsquo;elle a appris sur les entreprises avec ses coll\u00e8gues.<\/p><h2><strong>Elizabeth Shively et la Journ\u00e9e internationale de la femme<\/strong><\/h2><p>En fin de compte, Elizabeth Shively est bien plus qu\u2019une simple repr\u00e9sentante des ventes. Elle joue vraiment un r\u00f4le important dans la culture d&rsquo;entreprise d\u2019Elasto Proxy, comme en t\u00e9moigne son leadership dans la c\u00e9l\u00e9bration de la <em>Journ\u00e9e internationale de la femme<\/em>. \u00ab J&rsquo;ai eu la chance incroyable d&rsquo;avoir connu tant de femmes fortes et belles dans ma vie \u00bb, a-t-elle r\u00e9cemment d\u00e9clar\u00e9 dans un article publi\u00e9 sur les r\u00e9seaux sociaux c\u00e9l\u00e9brant cet \u00e9v\u00e9nement du 8 mars. \u00ab J&rsquo;esp\u00e8re \u00eatre un jour un encouragement pour d&rsquo;autres femmes \u00e0 poursuivre leurs r\u00eaves, peu importe si d&rsquo;autres les comprennent ou non \u00bb.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Elizabeth Shively est repr\u00e9sentante des ventes pour Elasto Proxy au si\u00e8ge social de la compagnie \u00e0 Boisbriand, Qu\u00e9bec, Canada. Originaire de Raymond, dans le Maine, aux \u00c9tats-Unis, elle a grandi dans une petite ville au bord du lac Sebago avant de s\u2019en aller vers le sud pour obtenir un dipl\u00f4me d&rsquo;ing\u00e9nieur en quatre ans \u00e0 [&hellip;]<\/p>\n","protected":false},"author":20,"featured_media":4732,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ofc_enable_fullscreen":"disable","ofc_fullscreen_speed":0,"ofc_fullscreen_nav":"enable","ofc_fullscreen_nav_pos":"right","ofc_fullscreen_nav_color":"","ofc_fullscreen_nav_tooltip_color":"","ofc_fullscreen_responsive":0,"osh_disable_topbar_sticky":"default","osh_disable_header_sticky":"default","osh_sticky_header_style":"default","osh_sticky_header_effect":"","osh_custom_sticky_logo":0,"osh_custom_retina_sticky_logo":0,"osh_custom_sticky_logo_height":0,"osh_background_color":"","osh_links_color":"","osh_links_hover_color":"","osh_links_active_color":"","osh_links_bg_color":"","osh_links_hover_bg_color":"","osh_links_active_bg_color":"","osh_menu_social_links_color":"","osh_menu_social_hover_links_color":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"off","ocean_gallery_id":[],"footnotes":""},"categories":[15],"tags":[550,647,648,568,649],"class_list":["post-4782","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee","tag-elastoproxy","tag-elastovie","tag-fabricants","tag-fabrication","tag-femmesenfabrication","entry","has-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Elizabeth Shively | Profiles d\u2019Elasto Proxy | Boisbriand, Qu\u00e9bec, Canada<\/title>\n<meta name=\"description\" content=\"Voici Elizabeth Shively, une repr\u00e9sentante des ventes pour Elasto Proxy au si\u00e8ge social de notre compagnie \u00e0 Boisbriand, Qu\u00e9bec, Canada.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.elastoproxy.com\/fr\/voici-elizabeth-shively\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Elizabeth Shively | Profiles d\u2019Elasto Proxy | Boisbriand, Qu\u00e9bec, Canada\" \/>\n<meta property=\"og:description\" content=\"Voici Elizabeth Shively, une repr\u00e9sentante des ventes pour Elasto Proxy au si\u00e8ge social de notre compagnie \u00e0 Boisbriand, Qu\u00e9bec, Canada.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.elastoproxy.com\/fr\/voici-elizabeth-shively\/\" \/>\n<meta property=\"og:site_name\" content=\"Elasto Proxy\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-16T18:23:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-03-16T18:24:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.elastoproxy.com\/wp-content\/uploads\/2019\/03\/Elizabeth-Shively-Profile-Image-857x1024.png\" \/>\n\t<meta property=\"og:image:width\" content=\"857\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Steve Melito\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Steve Melito\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Elizabeth Shively | Profiles d\u2019Elasto Proxy | Boisbriand, Qu\u00e9bec, Canada","description":"Voici Elizabeth Shively, une repr\u00e9sentante des ventes pour Elasto Proxy au si\u00e8ge social de notre compagnie \u00e0 Boisbriand, Qu\u00e9bec, Canada.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.elastoproxy.com\/fr\/voici-elizabeth-shively\/","og_locale":"fr_FR","og_type":"article","og_title":"Elizabeth Shively | Profiles d\u2019Elasto Proxy | Boisbriand, Qu\u00e9bec, Canada","og_description":"Voici Elizabeth Shively, une repr\u00e9sentante des ventes pour Elasto Proxy au si\u00e8ge social de notre compagnie \u00e0 Boisbriand, Qu\u00e9bec, Canada.","og_url":"https:\/\/www.elastoproxy.com\/fr\/voici-elizabeth-shively\/","og_site_name":"Elasto Proxy","article_published_time":"2019-03-16T18:23:31+00:00","article_modified_time":"2019-03-16T18:24:46+00:00","og_image":[{"width":857,"height":1024,"url":"https:\/\/www.elastoproxy.com\/wp-content\/uploads\/2019\/03\/Elizabeth-Shively-Profile-Image-857x1024.png","type":"image\/png"}],"author":"Steve Melito","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Steve Melito","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.elastoproxy.com\/fr\/voici-elizabeth-shively\/#article","isPartOf":{"@id":"https:\/\/www.elastoproxy.com\/fr\/voici-elizabeth-shively\/"},"author":{"name":"Steve Melito","@id":"https:\/\/www.elastoproxy.com\/#\/schema\/person\/54c278304f2b3726bb8de1bb1b5df225"},"headline":"Profiles d\u2019Elasto Proxy: voici Elizabeth Shively","datePublished":"2019-03-16T18:23:31+00:00","dateModified":"2019-03-16T18:24:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.elastoproxy.com\/fr\/voici-elizabeth-shively\/"},"wordCount":1034,"commentCount":0,"publisher":{"@id":"https:\/\/www.elastoproxy.com\/#organization"},"image":{"@id":"https:\/\/www.elastoproxy.com\/fr\/voici-elizabeth-shively\/#primaryimage"},"thumbnailUrl":"https:\/\/www.elastoproxy.com\/wp-content\/uploads\/2019\/03\/Elizabeth-Shively-Profile-Image.png","keywords":["#ElastoProxy","#ElastoVie","#fabricants","#Fabrication","#femmesenfabrication"],"articleSection":["Non classifi\u00e9(e)"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.elastoproxy.com\/fr\/voici-elizabeth-shively\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.elastoproxy.com\/fr\/voici-elizabeth-shively\/","url":"https:\/\/www.elastoproxy.com\/fr\/voici-elizabeth-shively\/","name":"Elizabeth Shively | Profiles d\u2019Elasto Proxy | Boisbriand, Qu\u00e9bec, Canada","isPartOf":{"@id":"https:\/\/www.elastoproxy.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.elastoproxy.com\/fr\/voici-elizabeth-shively\/#primaryimage"},"image":{"@id":"https:\/\/www.elastoproxy.com\/fr\/voici-elizabeth-shively\/#primaryimage"},"thumbnailUrl":"https:\/\/www.elastoproxy.com\/wp-content\/uploads\/2019\/03\/Elizabeth-Shively-Profile-Image.png","datePublished":"2019-03-16T18:23:31+00:00","dateModified":"2019-03-16T18:24:46+00:00","description":"Voici Elizabeth Shively, une repr\u00e9sentante des ventes pour Elasto Proxy au si\u00e8ge social de notre compagnie \u00e0 Boisbriand, Qu\u00e9bec, Canada.","breadcrumb":{"@id":"https:\/\/www.elastoproxy.com\/fr\/voici-elizabeth-shively\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.elastoproxy.com\/fr\/voici-elizabeth-shively\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.elastoproxy.com\/fr\/voici-elizabeth-shively\/#primaryimage","url":"https:\/\/www.elastoproxy.com\/wp-content\/uploads\/2019\/03\/Elizabeth-Shively-Profile-Image.png","contentUrl":"https:\/\/www.elastoproxy.com\/wp-content\/uploads\/2019\/03\/Elizabeth-Shively-Profile-Image.png","width":3024,"height":3615,"caption":"Elizabeth Shively"},{"@type":"BreadcrumbList","@id":"https:\/\/www.elastoproxy.com\/fr\/voici-elizabeth-shively\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.elastoproxy.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Profiles d\u2019Elasto Proxy: voici Elizabeth Shively"}]},{"@type":"WebSite","@id":"https:\/\/www.elastoproxy.com\/#website","url":"https:\/\/www.elastoproxy.com\/","name":"Elasto Proxy","description":"Rubber Fabricator and Distributor","publisher":{"@id":"https:\/\/www.elastoproxy.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.elastoproxy.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.elastoproxy.com\/#organization","name":"Elasto Proxy","url":"https:\/\/www.elastoproxy.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.elastoproxy.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.elastoproxy.com\/wp-content\/uploads\/2018\/10\/logo-elastoproxy.png","contentUrl":"https:\/\/www.elastoproxy.com\/wp-content\/uploads\/2018\/10\/logo-elastoproxy.png","width":200,"height":61,"caption":"Elasto Proxy"},"image":{"@id":"https:\/\/www.elastoproxy.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.elastoproxy.com\/#\/schema\/person\/54c278304f2b3726bb8de1bb1b5df225","name":"Steve Melito","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.elastoproxy.com\/#\/schema\/person\/image\/","url":"https:\/\/www.elastoproxy.com\/wp-content\/litespeed\/avatar\/cf7233bebd28fab336564db23356c33b.jpg?ver=1784028787","contentUrl":"https:\/\/www.elastoproxy.com\/wp-content\/litespeed\/avatar\/cf7233bebd28fab336564db23356c33b.jpg?ver=1784028787","caption":"Steve Melito"},"url":"https:\/\/www.elastoproxy.com\/fr\/author\/smelito\/"}]}},"_links":{"self":[{"href":"https:\/\/www.elastoproxy.com\/fr\/wp-json\/wp\/v2\/posts\/4782","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elastoproxy.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.elastoproxy.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.elastoproxy.com\/fr\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elastoproxy.com\/fr\/wp-json\/wp\/v2\/comments?post=4782"}],"version-history":[{"count":2,"href":"https:\/\/www.elastoproxy.com\/fr\/wp-json\/wp\/v2\/posts\/4782\/revisions"}],"predecessor-version":[{"id":4784,"href":"https:\/\/www.elastoproxy.com\/fr\/wp-json\/wp\/v2\/posts\/4782\/revisions\/4784"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.elastoproxy.com\/fr\/wp-json\/wp\/v2\/media\/4732"}],"wp:attachment":[{"href":"https:\/\/www.elastoproxy.com\/fr\/wp-json\/wp\/v2\/media?parent=4782"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.elastoproxy.com\/fr\/wp-json\/wp\/v2\/categories?post=4782"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.elastoproxy.com\/fr\/wp-json\/wp\/v2\/tags?post=4782"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}