{"id":17508,"date":"2021-12-03T19:17:54","date_gmt":"2021-12-04T00:17:54","guid":{"rendered":"https:\/\/www.elastoproxy.com\/?p=17508"},"modified":"2021-12-03T19:19:44","modified_gmt":"2021-12-04T00:19:44","slug":"bons-produits-en-caoutchouc","status":"publish","type":"post","link":"https:\/\/www.elastoproxy.com\/fr\/bons-produits-en-caoutchouc\/","title":{"rendered":"Les mauvaises raisons r\u00e9pondent aux bons produits en caoutchouc"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"17508\" class=\"elementor elementor-17508\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-83a8ee6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"83a8ee6\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2b6c153\" data-id=\"2b6c153\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9ce1186 elementor-widget elementor-widget-text-editor\" data-id=\"9ce1186\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Qu\u2019est-ce qui emp\u00eache davantage d\u2019entreprises d\u2019acheter les bons produits en caoutchouc? Est-ce parce qu\u2019ils n\u2019ont pas l\u2019information dont ils ont besoin pour prendre des d\u00e9cisions \u00e9clair\u00e9es?\u00a0\u00a0 Ou est-ce parce que ce qu\u2019ils pensent savoir n\u2019est pas toujours conforme \u00e0 la r\u00e9alit\u00e9 ? Il y a aussi des moments o\u00f9 les entreprises ne savent pas encore ce qu\u2019elles ne savent pas. En d\u2019autres termes, il y a des co\u00fbts et des risques que certaines entreprises n\u2019ont pas encore pris en compte.<\/p><p>Si vous achetez de petits \u00e0 moyens volumes de produits en caoutchouc, vous pourriez convenir \u00e0\u00a0 <a href=\"https:\/\/www.elastoproxy.com\/\">Elasto Proxy<\/a>. Les pi\u00e8ces en caoutchouc comme les plates-formes O sont des achats de produits de base, mais nous ne sommes pas une entreprise de produits de base. Au lieu de cela, nous nous sp\u00e9cialisons dans les produits fabriqu\u00e9s sur mesure et nous offrons des services \u00e0 valeur ajout\u00e9e. Donc, si vous recherchez les bons produits en caoutchouc, assurez-vous de ne pas les rater pour les mauvaises raisons. Il y en a quatre.<\/p><ul><li>Le budget<\/li><li>La confiance<\/li><li>Le besoin<\/li><li>L\u2019urgence<\/li><\/ul><p>Jetons un coup d\u2019\u0153il sur chacune d\u2019elles.<\/p><h2><strong>Le budget <\/strong><\/h2><p>Pensez-vous qu\u2019Elasto Proxy est trop cher? Chaque projet a un budget, et les bons produits en caoutchouc ne peuvent pas causer de d\u00e9passements de co\u00fbts majeurs. Mais seriez-vous pr\u00eat \u00e0 payer 15% ou m\u00eame 20% de plus si la valeur ajout\u00e9e que vous recevez r\u00e9duit vos co\u00fbts d\u2019exploitation? Lorsque vous travaillez avec Elasto Proxy nous prenons le temps de comprendre vos processus d\u2019op\u00e9ration afin que nous puissions trouver des moyens pour vous faire \u00e9conomiser du temps et de l\u2019argent.<\/p><p>Par exemple, supposons que vous installiez des joints de porte avec du ruban adh\u00e9sif sensible \u00e0 la pression (PSA). Vos op\u00e9rateurs peuvent couper du ruban sur la cha\u00eene de montage, ou vous pouvez pr\u00e9-couper du ruban d\u2019Elasto Proxy. Si l\u2019utilisation de notre ruban pr\u00e9d\u00e9coup\u00e9 vous permet d\u2019\u00e9conomiser cinq minutes par porte, combien \u00e9conomiseriez-vous sur tous les joints de porte que vous installez au cours d\u2019une ann\u00e9e?\u00a0 Et combien \u00e9conomiseriez-vous sur les mat\u00e9riaux en raison de moins de mauvaises coupures?<\/p><h2><strong>La confiance<\/strong><\/h2><p>H\u00e9sitez-vous \u00e0 travailler avec nous parce que vous n\u2019avez jamais entendu parler d\u2019Elasto Proxy? Notre entreprise canadienne a \u00e9t\u00e9 fond\u00e9e en 1989 et elle est familiale. \u00a0Aujourd\u2019hui, nous sommes certifi\u00e9s ISO 9001: 2015 et <a href=\"https:\/\/www.nqa.com\/en-us\/certification\/standards\/as9100\">AS9100 Rev. D<\/a> En tant que membre inscrit du Programme des marchandises contr\u00f4l\u00e9es (PMC) du Canada, nous r\u00e9pondons \u00e0 des exigences strictes en mati\u00e8re de tenue de dossiers, de programmes de formation, de s\u00e9ances d\u2019information sur la s\u00e9curit\u00e9 et d\u2019inspections.<\/p><p>Toujours pas convaincu? Elasto Proxy fournit General Dynamics, Textron, Tesla, Volvo Group et Nova Bus &#8211; pour ne nommer que quelques entreprises bien connues. Mais qu\u2019en est-il de vous? Que se passe-t-il si nous vous offrons un essai sans risque comme nous l\u2019avons fait pour un grand fabricant d\u2019\u00e9quipement lourd? L\u2019OEM-FEO (Original Equipment Manufacturer \u2013 Fabricant d\u2019\u00e9quipement d\u2019origine) nous a donn\u00e9 deux mois de production de joints, et nous avons accept\u00e9 de leur donner du cr\u00e9dit si nous ne leur faisions pas \u00e9conomiser de l\u2019argent.<\/p><h2><strong>Le besoin<\/strong><\/h2><p>Vous n\u2019\u00eates pas s\u00fbr que nous ayons ce dont vous avez besoin? Elasto Proxy est \u00e0 la fois un distributeur et un fabricant. Donc, que vous ayez besoin de bobines de caoutchouc, de mat\u00e9riaux en feuille, de longueurs pr\u00e9d\u00e9coup\u00e9es ou de produits finis comme des joints faits sur mesure ou une isolation acoustique, nous prendrons soin de vous. Si vous recherchez des bobines en caoutchouc, nous pouvons vous exp\u00e9dier des quantit\u00e9s aussi petites que 10,000 pieds. Si vous avez besoin de produits finis, nous pouvons ajouter de la valeur avec des emballages de kitting et d\u2019assemblage.\u00a0\u00a0<\/p><p>Mais vous avez aussi des besoins commerciaux. Pr\u00e9occup\u00e9 par les flux de tr\u00e9sorerie?\u00a0 Qu\u2019en est-il de la disponibilit\u00e9 des pi\u00e8ces? Commandez tout ce dont vous avez besoin pendant un an, puis faites lib\u00e9rer les quantit\u00e9s d\u2019Elasto Proxy en fonction de vos pr\u00e9visions de ventes. Nous ne vous facturerons pas tant que nous ne l\u2019exp\u00e9dierons pas, et vous aimerez les livraisons \u00e0 temps.\u00a0 Avec la qualit\u00e9 que vous obtiendrez de nous, vous pouvez aussi r\u00e9duire les co\u00fbts de r\u00e9paration et oublier \u00e0 devoir retravailler les joints en caoutchouc.\u00a0<\/p><h2><strong>L\u2019urgence et les bons produits en caoutchouc<\/strong><\/h2><p>Pensez-vous que le probl\u00e8me que nous pouvons r\u00e9soudre n\u2019est pas si important pour vous en ce moment?\u00a0 Nous comprenons que vous \u00eates occup\u00e9, mais ce que nous demandons, c\u2019est 10 minutes de votre temps. Et ces 10 minutes pourraient vous faire \u00e9conomiser beaucoup plus de temps (et d\u2019argent) \u00e0 l\u2019avenir. Si cela ressemble \u00e0 la publicit\u00e9 Geico \u00e0 la t\u00e9l\u00e9 pour l\u2019assurance automobile ce n\u2019est pas grave. Peut-\u00eatre que cette publicit\u00e9 vous colle \u00e0 l\u2019esprit parce que c\u2019est logique.<\/p><p>Dans votre \u00e9tablissement, quel est le co\u00fbt horaire d\u2019un arr\u00eat de travail sur votre cha\u00eene de montage? Si vous n\u2019avez pas ou ne pouvez pas obtenir les bons produits en caoutchouc, pourriez-vous vivre quelque chose comme ce que l\u2019industrie automobile traverse avec la p\u00e9nurie de puces? Les v\u00e9hicules sont en grande partie assembl\u00e9s, mais il leur manque des pi\u00e8ces. Cela augmente la quantit\u00e9 de travail en cours &#8211; et les prix continuent d\u2019augmenter, aussi.<\/p><p>Ne laissez pas les mauvaises raisons vous emp\u00eacher d\u2019obtenir les bons produits en caoutchouc.<\/p><p><a href=\"https:\/\/www.elastoproxy.com\/contact-us\/\">Parlez \u00e0 Elasto Proxy.<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Ne laissez pas les mauvaises raisons vous emp\u00eacher d\u2019obtenir les bons produits en caoutchouc. Examinez le budget, la confiance, les besoins et l\u2019urgence. Parlez \u00e0 Elasto Proxy.<\/p>\n","protected":false},"author":20,"featured_media":4226,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","ofc_enable_fullscreen":"disable","ofc_fullscreen_speed":0,"ofc_fullscreen_nav":"enable","ofc_fullscreen_nav_pos":"right","ofc_fullscreen_nav_color":"","ofc_fullscreen_nav_tooltip_color":"","ofc_fullscreen_responsive":0,"osh_disable_topbar_sticky":"default","osh_disable_header_sticky":"default","osh_sticky_header_style":"default","osh_sticky_header_effect":"","osh_custom_sticky_logo":0,"osh_custom_retina_sticky_logo":0,"osh_custom_sticky_logo_height":0,"osh_background_color":"","osh_links_color":"","osh_links_hover_color":"","osh_links_active_color":"","osh_links_bg_color":"","osh_links_hover_bg_color":"","osh_links_active_bg_color":"","osh_menu_social_links_color":"","osh_menu_social_hover_links_color":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"off","ocean_gallery_id":[],"footnotes":""},"categories":[15],"tags":[],"class_list":["post-17508","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee","entry","has-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>De bons produits en caoutchouc | Budget, confiance, besoin et urgence | Elasto Proxy<\/title>\n<meta name=\"description\" content=\"Ne laissez pas les mauvaises raisons vous emp\u00eacher d\u2019obtenir les bons produits en caoutchouc. Examinez le budget, la confiance, les besoins et l\u2019urgence. Parlez \u00e0 Elasto Proxy.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.elastoproxy.com\/fr\/bons-produits-en-caoutchouc\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"De bons produits en caoutchouc | Budget, confiance, besoin et urgence | Elasto Proxy\" \/>\n<meta property=\"og:description\" content=\"Ne laissez pas les mauvaises raisons vous emp\u00eacher d\u2019obtenir les bons produits en caoutchouc. Examinez le budget, la confiance, les besoins et l\u2019urgence. Parlez \u00e0 Elasto Proxy.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.elastoproxy.com\/fr\/bons-produits-en-caoutchouc\/\" \/>\n<meta property=\"og:site_name\" content=\"Elasto Proxy\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-04T00:17:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-04T00:19:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.elastoproxy.com\/wp-content\/uploads\/2018\/12\/DSC_4194-1024x681.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"681\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Steve Melito\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Steve Melito\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"De bons produits en caoutchouc | Budget, confiance, besoin et urgence | Elasto Proxy","description":"Ne laissez pas les mauvaises raisons vous emp\u00eacher d\u2019obtenir les bons produits en caoutchouc. Examinez le budget, la confiance, les besoins et l\u2019urgence. Parlez \u00e0 Elasto Proxy.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.elastoproxy.com\/fr\/bons-produits-en-caoutchouc\/","og_locale":"fr_FR","og_type":"article","og_title":"De bons produits en caoutchouc | Budget, confiance, besoin et urgence | Elasto Proxy","og_description":"Ne laissez pas les mauvaises raisons vous emp\u00eacher d\u2019obtenir les bons produits en caoutchouc. Examinez le budget, la confiance, les besoins et l\u2019urgence. Parlez \u00e0 Elasto Proxy.","og_url":"https:\/\/www.elastoproxy.com\/fr\/bons-produits-en-caoutchouc\/","og_site_name":"Elasto Proxy","article_published_time":"2021-12-04T00:17:54+00:00","article_modified_time":"2021-12-04T00:19:44+00:00","og_image":[{"width":1024,"height":681,"url":"https:\/\/www.elastoproxy.com\/wp-content\/uploads\/2018\/12\/DSC_4194-1024x681.jpg","type":"image\/jpeg"}],"author":"Steve Melito","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Steve Melito","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.elastoproxy.com\/fr\/bons-produits-en-caoutchouc\/#article","isPartOf":{"@id":"https:\/\/www.elastoproxy.com\/fr\/bons-produits-en-caoutchouc\/"},"author":{"name":"Steve Melito","@id":"https:\/\/www.elastoproxy.com\/#\/schema\/person\/54c278304f2b3726bb8de1bb1b5df225"},"headline":"Les mauvaises raisons r\u00e9pondent aux bons produits en caoutchouc","datePublished":"2021-12-04T00:17:54+00:00","dateModified":"2021-12-04T00:19:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.elastoproxy.com\/fr\/bons-produits-en-caoutchouc\/"},"wordCount":979,"commentCount":0,"publisher":{"@id":"https:\/\/www.elastoproxy.com\/#organization"},"image":{"@id":"https:\/\/www.elastoproxy.com\/fr\/bons-produits-en-caoutchouc\/#primaryimage"},"thumbnailUrl":"https:\/\/www.elastoproxy.com\/wp-content\/uploads\/2018\/12\/DSC_4194.jpg","articleSection":["Non classifi\u00e9(e)"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.elastoproxy.com\/fr\/bons-produits-en-caoutchouc\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.elastoproxy.com\/fr\/bons-produits-en-caoutchouc\/","url":"https:\/\/www.elastoproxy.com\/fr\/bons-produits-en-caoutchouc\/","name":"De bons produits en caoutchouc | Budget, confiance, besoin et urgence | Elasto Proxy","isPartOf":{"@id":"https:\/\/www.elastoproxy.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.elastoproxy.com\/fr\/bons-produits-en-caoutchouc\/#primaryimage"},"image":{"@id":"https:\/\/www.elastoproxy.com\/fr\/bons-produits-en-caoutchouc\/#primaryimage"},"thumbnailUrl":"https:\/\/www.elastoproxy.com\/wp-content\/uploads\/2018\/12\/DSC_4194.jpg","datePublished":"2021-12-04T00:17:54+00:00","dateModified":"2021-12-04T00:19:44+00:00","description":"Ne laissez pas les mauvaises raisons vous emp\u00eacher d\u2019obtenir les bons produits en caoutchouc. Examinez le budget, la confiance, les besoins et l\u2019urgence. Parlez \u00e0 Elasto Proxy.","breadcrumb":{"@id":"https:\/\/www.elastoproxy.com\/fr\/bons-produits-en-caoutchouc\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.elastoproxy.com\/fr\/bons-produits-en-caoutchouc\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.elastoproxy.com\/fr\/bons-produits-en-caoutchouc\/#primaryimage","url":"https:\/\/www.elastoproxy.com\/wp-content\/uploads\/2018\/12\/DSC_4194.jpg","contentUrl":"https:\/\/www.elastoproxy.com\/wp-content\/uploads\/2018\/12\/DSC_4194.jpg","width":3008,"height":2000,"caption":"sponge rubber gaskets vs. solid rubber gaskets | Joints en caoutchouc \u00e9ponge vs joints en caoutchouc solide"},{"@type":"BreadcrumbList","@id":"https:\/\/www.elastoproxy.com\/fr\/bons-produits-en-caoutchouc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.elastoproxy.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Les mauvaises raisons r\u00e9pondent aux bons produits en caoutchouc"}]},{"@type":"WebSite","@id":"https:\/\/www.elastoproxy.com\/#website","url":"https:\/\/www.elastoproxy.com\/","name":"Elasto Proxy","description":"Rubber Fabricator and Distributor","publisher":{"@id":"https:\/\/www.elastoproxy.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.elastoproxy.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.elastoproxy.com\/#organization","name":"Elasto Proxy","url":"https:\/\/www.elastoproxy.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.elastoproxy.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.elastoproxy.com\/wp-content\/uploads\/2018\/10\/logo-elastoproxy.png","contentUrl":"https:\/\/www.elastoproxy.com\/wp-content\/uploads\/2018\/10\/logo-elastoproxy.png","width":200,"height":61,"caption":"Elasto Proxy"},"image":{"@id":"https:\/\/www.elastoproxy.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.elastoproxy.com\/#\/schema\/person\/54c278304f2b3726bb8de1bb1b5df225","name":"Steve Melito","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.elastoproxy.com\/#\/schema\/person\/image\/","url":"https:\/\/www.elastoproxy.com\/wp-content\/litespeed\/avatar\/cf7233bebd28fab336564db23356c33b.jpg?ver=1784028787","contentUrl":"https:\/\/www.elastoproxy.com\/wp-content\/litespeed\/avatar\/cf7233bebd28fab336564db23356c33b.jpg?ver=1784028787","caption":"Steve Melito"},"url":"https:\/\/www.elastoproxy.com\/fr\/author\/smelito\/"}]}},"_links":{"self":[{"href":"https:\/\/www.elastoproxy.com\/fr\/wp-json\/wp\/v2\/posts\/17508","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elastoproxy.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.elastoproxy.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.elastoproxy.com\/fr\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elastoproxy.com\/fr\/wp-json\/wp\/v2\/comments?post=17508"}],"version-history":[{"count":5,"href":"https:\/\/www.elastoproxy.com\/fr\/wp-json\/wp\/v2\/posts\/17508\/revisions"}],"predecessor-version":[{"id":17513,"href":"https:\/\/www.elastoproxy.com\/fr\/wp-json\/wp\/v2\/posts\/17508\/revisions\/17513"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.elastoproxy.com\/fr\/wp-json\/wp\/v2\/media\/4226"}],"wp:attachment":[{"href":"https:\/\/www.elastoproxy.com\/fr\/wp-json\/wp\/v2\/media?parent=17508"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.elastoproxy.com\/fr\/wp-json\/wp\/v2\/categories?post=17508"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.elastoproxy.com\/fr\/wp-json\/wp\/v2\/tags?post=17508"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}